{"id":7241,"date":"2020-05-01T13:06:23","date_gmt":"2020-05-01T11:06:23","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=7241"},"modified":"2026-06-01T10:13:55","modified_gmt":"2026-06-01T08:13:55","slug":"perpetual-calendar-42-iw344203","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/","title":{"rendered":"IWC Portugieser Perpetual Calendar 42"},"content":{"rendered":"<p>Mit dem Modell Pertpetual Calendar 42 in Edelstahl hat IWC Schaffhausen es erstmals geschafft, das bekannte Kalenderwerk in eines der kompakten Uhrwerke der Kaliberfamilie 82000 zu integrieren. Die Portugieser Ewiger Kalender bietet exakte Zeitmessung auf einem Durchmesser von 42.4 Millimetern. Die Kalenderfunktion wird \u00fcber drei Hilfszifferbl\u00e4tter realisiert. Bei der Entwicklung dieses hochwertigen Modells stand die einfache Bedienung im Vordergrund, die trotz der komplexen Funktionen gew\u00e4hrleistet sein sollte. Der Perpetual Calendar basiert auf einer Entwicklung der Uhrmacher-Legende Kurt Klaus aus den 1980er-Jahren.<\/p>\n<p>Der nahezu verschleissfreie Pellaton Automatik-Aufzug ist mit hochwertigen Zirkonoxid-Kreamik-Komponenten ausgestattet und kann eine Gangreserve von bis zu 60 Stunden aufbauen. Dieses hervorragende und komplexe Uhrwerk kann \u2013 wie bei den Portugiesern \u00fcblich \u2013 mittels Saphirglas-Sichtboden in Augenschein genommen werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem Modell Pertpetual Calendar 42 in Edelstahl hat IWC Schaffhausen es erstmals geschafft, das bekannte Kalenderwerk in eines der kompakten Uhrwerke der Kaliberfamilie 82000 zu integrieren. Die Portugieser Ewiger Kalender bietet exakte Zeitmessung auf einem Durchmesser von 42.4 Millimetern. Die Kalenderfunktion wird \u00fcber drei Hilfszifferbl\u00e4tter realisiert. Bei der Entwicklung dieses hochwertigen Modells stand die&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/\" title=\"Read IWC Portugieser Perpetual Calendar 42\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":7205,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-7241","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-iwc","uhrenhersteller-portugieser","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IWC Portugieser Perpetual Calendar 42 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IWC Portugieser Perpetual Calendar 42 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Mit dem Modell Pertpetual Calendar 42 in Edelstahl hat IWC Schaffhausen es erstmals geschafft, das bekannte Kalenderwerk in eines der kompakten Uhrwerke der Kaliberfamilie 82000 zu integrieren. Die Portugieser Ewiger Kalender bietet exakte Zeitmessung auf einem Durchmesser von 42.4 Millimetern. Die Kalenderfunktion wird \u00fcber drei Hilfszifferbl\u00e4tter realisiert. Bei der Entwicklung dieses hochwertigen Modells stand die... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:13:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iw344203.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/\",\"name\":\"IWC Portugieser Perpetual Calendar 42 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/iw344203.png\",\"datePublished\":\"2020-05-01T11:06:23+00:00\",\"dateModified\":\"2026-06-01T08:13:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/iw344203.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/iw344203.png\",\"width\":1000,\"height\":1400,\"caption\":\"iwc-portugieser-ewiger-kalender-edelstahl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/perpetual-calendar-42-iw344203\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IWC Portugieser Perpetual Calendar 42\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IWC Portugieser Perpetual Calendar 42 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/","og_locale":"en_US","og_type":"article","og_title":"IWC Portugieser Perpetual Calendar 42 - Galli Uhren Bijouterie","og_description":"Mit dem Modell Pertpetual Calendar 42 in Edelstahl hat IWC Schaffhausen es erstmals geschafft, das bekannte Kalenderwerk in eines der kompakten Uhrwerke der Kaliberfamilie 82000 zu integrieren. Die Portugieser Ewiger Kalender bietet exakte Zeitmessung auf einem Durchmesser von 42.4 Millimetern. Die Kalenderfunktion wird \u00fcber drei Hilfszifferbl\u00e4tter realisiert. Bei der Entwicklung dieses hochwertigen Modells stand die... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:13:55+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iw344203.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/","url":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/","name":"IWC Portugieser Perpetual Calendar 42 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iw344203.png","datePublished":"2020-05-01T11:06:23+00:00","dateModified":"2026-06-01T08:13:55+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iw344203.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iw344203.png","width":1000,"height":1400,"caption":"iwc-portugieser-ewiger-kalender-edelstahl"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/perpetual-calendar-42-iw344203\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"IWC Portugieser Perpetual Calendar 42"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/7241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/7205"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=7241"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=7241"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=7241"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=7241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}