{"id":6985,"date":"2020-04-07T15:51:12","date_gmt":"2020-04-07T13:51:12","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=6985"},"modified":"2026-06-01T10:17:30","modified_gmt":"2026-06-01T08:17:30","slug":"constellation-master-chronometer-39mm-131-20-39-20-02-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/","title":{"rendered":"Omega Constellation Master Chronometer 39"},"content":{"rendered":"<p>Das dramatische und best\u00e4ndige Design der OMEGA Constellation zeichnet sich durch seine ber\u00fchmten Halbmonde, die &#8220;Krallen&#8221; am Geh\u00e4use und das einreihige Armband aus.<\/p>\n<p>Dieses Modell aus 39 mm Edelstahl und 18K Sedna\u2122 Gold verf\u00fcgt \u00fcber eine mit r\u00f6mischen Ziffern gravierte L\u00fcnette, ein opalweiss-silbriges Zifferblatt und ein Datumsfenster bei der 6-Uhr-Position. Die Zeiger, das OMEGA-Logo, der Stern der Constellation und die Indexe sind alle aus 18K Sedna\u2122 Gold.<\/p>\n<p>Das Herzst\u00fcck dieses Zeitmessers ist das OMEGA Co-Axial Master Chronometer Calibre 8800, das durch das gew\u00f6lbte, kratzfeste Saphirglas sichtbar ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das dramatische und best\u00e4ndige Design der OMEGA Constellation zeichnet sich durch seine ber\u00fchmten Halbmonde, die &#8220;Krallen&#8221; am Geh\u00e4use und das einreihige Armband aus. Dieses Modell aus 39 mm Edelstahl und 18K Sedna\u2122 Gold verf\u00fcgt \u00fcber eine mit r\u00f6mischen Ziffern gravierte L\u00fcnette, ein opalweiss-silbriges Zifferblatt und ein Datumsfenster bei der 6-Uhr-Position. Die Zeiger, das OMEGA-Logo, der&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/\" title=\"Read Omega Constellation Master Chronometer 39\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":6950,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-6985","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-constellation","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Constellation Master Chronometer 39 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Constellation Master Chronometer 39 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Das dramatische und best\u00e4ndige Design der OMEGA Constellation zeichnet sich durch seine ber\u00fchmten Halbmonde, die &#8220;Krallen&#8221; am Geh\u00e4use und das einreihige Armband aus. Dieses Modell aus 39 mm Edelstahl und 18K Sedna\u2122 Gold verf\u00fcgt \u00fcber eine mit r\u00f6mischen Ziffern gravierte L\u00fcnette, ein opalweiss-silbriges Zifferblatt und ein Datumsfenster bei der 6-Uhr-Position. Die Zeiger, das OMEGA-Logo, der... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:17:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/\",\"name\":\"Omega Constellation Master Chronometer 39 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png\",\"datePublished\":\"2020-04-07T13:51:12+00:00\",\"dateModified\":\"2026-06-01T08:17:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png\",\"width\":1000,\"height\":1400,\"caption\":\"constellation-master-chronometer-39mm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/constellation-master-chronometer-39mm-131-20-39-20-02-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Constellation Master Chronometer 39\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Constellation Master Chronometer 39 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Constellation Master Chronometer 39 - Galli Uhren Bijouterie","og_description":"Das dramatische und best\u00e4ndige Design der OMEGA Constellation zeichnet sich durch seine ber\u00fchmten Halbmonde, die &#8220;Krallen&#8221; am Geh\u00e4use und das einreihige Armband aus. Dieses Modell aus 39 mm Edelstahl und 18K Sedna\u2122 Gold verf\u00fcgt \u00fcber eine mit r\u00f6mischen Ziffern gravierte L\u00fcnette, ein opalweiss-silbriges Zifferblatt und ein Datumsfenster bei der 6-Uhr-Position. Die Zeiger, das OMEGA-Logo, der... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:17:30+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/","name":"Omega Constellation Master Chronometer 39 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png","datePublished":"2020-04-07T13:51:12+00:00","dateModified":"2026-06-01T08:17:30+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-omega-co-axial-master-chronometer-39-mm-13120392002001-1-product-zoom.png","width":1000,"height":1400,"caption":"constellation-master-chronometer-39mm"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/constellation-master-chronometer-39mm-131-20-39-20-02-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Constellation Master Chronometer 39"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/6985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/6950"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=6985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=6985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=6985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=6985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}