{"id":6223,"date":"2019-10-02T19:11:44","date_gmt":"2019-10-02T17:11:44","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=6223"},"modified":"2025-03-13T13:44:21","modified_gmt":"2025-03-13T12:44:21","slug":"automatic-moon-phase-iw459402","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/","title":{"rendered":"IWC Portofino Automatic Moon Phase"},"content":{"rendered":"<p>1984 hat IWC die Portofino-Kollektion kreiert. Benannt wurde die Familie nach dem idyllischen Dorf an der italienischen K\u00fcste, das sich in den 1950er- und 1960er-Jahren zu einer exklusiven Feriendestination f\u00fcr den internationalen Jet-Set entwickelte. Seither vereinen Portofino-Uhren erfolgreich die Leichtigkeit der mediterranen Lebensart mit einem Hauch von Luxus und Eleganz. Die Portofino Automatic Moon Phase ist die erste Portofino-Uhr mit einem Geh\u00e4usedurchmesser von 40 Millimetern, welche mit einer Anzeige f\u00fcr die Mondphase ausgestattet ist. Bisher ins Jahr 2018 wurde diese beliebte Komplikation nur in 45 Millimetern oder 37 Millimetern angeboten.<\/p>\n<p>Der Zeitmesser ist in ein klassisches Geh\u00e4use aus Edelstahl gefasst. Der silberne Mond harmoniert sch\u00f6n mit dem blauen Zifferblatt und den rhodinierten Zeigern und Appliken. Die schlichte und gleichzeitig elegante Armbanduhr wird an einem schwarzen, von Hand gef\u00e4rbten Armband aus Alligatorleder getragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1984 hat IWC die Portofino-Kollektion kreiert. Benannt wurde die Familie nach dem idyllischen Dorf an der italienischen K\u00fcste, das sich in den 1950er- und 1960er-Jahren zu einer exklusiven Feriendestination f\u00fcr den internationalen Jet-Set entwickelte. Seither vereinen Portofino-Uhren erfolgreich die Leichtigkeit der mediterranen Lebensart mit einem Hauch von Luxus und Eleganz. Die Portofino Automatic Moon Phase&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/\" title=\"Read IWC Portofino Automatic Moon Phase\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":6122,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-6223","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-iwc","uhrenhersteller-portofino","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IWC Portofino Automatic Moon Phase - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IWC Portofino Automatic Moon Phase - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"1984 hat IWC die Portofino-Kollektion kreiert. Benannt wurde die Familie nach dem idyllischen Dorf an der italienischen K\u00fcste, das sich in den 1950er- und 1960er-Jahren zu einer exklusiven Feriendestination f\u00fcr den internationalen Jet-Set entwickelte. Seither vereinen Portofino-Uhren erfolgreich die Leichtigkeit der mediterranen Lebensart mit einem Hauch von Luxus und Eleganz. Die Portofino Automatic Moon Phase... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T12:44:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iwc-459402-537537-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/\",\"name\":\"IWC Portofino Automatic Moon Phase - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/iwc-459402-537537-1.png\",\"datePublished\":\"2019-10-02T17:11:44+00:00\",\"dateModified\":\"2025-03-13T12:44:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/iwc-459402-537537-1.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/iwc-459402-537537-1.png\",\"width\":1000,\"height\":1400,\"caption\":\"IWC Portofino Moon Phase Galli Z\u00fcrich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portofino\\\/automatic-moon-phase-iw459402\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Portofino Automatic Moon Phase\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IWC Portofino Automatic Moon Phase - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/","og_locale":"en_US","og_type":"article","og_title":"IWC Portofino Automatic Moon Phase - Galli Uhren Bijouterie","og_description":"1984 hat IWC die Portofino-Kollektion kreiert. Benannt wurde die Familie nach dem idyllischen Dorf an der italienischen K\u00fcste, das sich in den 1950er- und 1960er-Jahren zu einer exklusiven Feriendestination f\u00fcr den internationalen Jet-Set entwickelte. Seither vereinen Portofino-Uhren erfolgreich die Leichtigkeit der mediterranen Lebensart mit einem Hauch von Luxus und Eleganz. Die Portofino Automatic Moon Phase... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-03-13T12:44:21+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iwc-459402-537537-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/","url":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/","name":"IWC Portofino Automatic Moon Phase - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iwc-459402-537537-1.png","datePublished":"2019-10-02T17:11:44+00:00","dateModified":"2025-03-13T12:44:21+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iwc-459402-537537-1.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/iwc-459402-537537-1.png","width":1000,"height":1400,"caption":"IWC Portofino Moon Phase Galli Z\u00fcrich"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portofino\/automatic-moon-phase-iw459402\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Portofino Automatic Moon Phase"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/6223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/6122"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=6223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=6223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=6223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=6223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}