{"id":561,"date":"2018-07-17T17:06:41","date_gmt":"2018-07-17T17:06:41","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=561"},"modified":"2026-06-01T10:16:18","modified_gmt":"2026-06-01T08:16:18","slug":"t-sport-9","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tissot\/t-sport\/t-sport-9\/","title":{"rendered":"Tissot Chrono XL Classic"},"content":{"rendered":"<p>Dieser sportliche Chronograph bietet eines der gr\u00f6ssten Geh\u00e4use der gesamten Tissot-Kollektion (45mm). Das kratzfeste Saphirglas sch\u00fctzt das Zifferblatt mit Indizes und arabischen Ziffern, welche eine Superluminova Beschichtung besitzen. Schweizer Technologie zu einem unschlagbaren Preis!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieser sportliche Chronograph bietet eines der gr\u00f6ssten Geh\u00e4use der gesamten Tissot-Kollektion (45mm). Das kratzfeste Saphirglas sch\u00fctzt das Zifferblatt mit Indizes und arabischen Ziffern, welche eine Superluminova Beschichtung besitzen. Schweizer Technologie zu einem unschlagbaren Preis!<\/p>\n","protected":false},"featured_media":535,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-561","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tissot","uhrenhersteller-t-sport","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tissot Chrono XL Classic - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tissot Chrono XL Classic - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Dieser sportliche Chronograph bietet eines der gr\u00f6ssten Geh\u00e4use der gesamten Tissot-Kollektion (45mm). Das kratzfeste Saphirglas sch\u00fctzt das Zifferblatt mit Indizes und arabischen Ziffern, welche eine Superluminova Beschichtung besitzen. Schweizer Technologie zu einem unschlagbaren Preis!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:16:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Tissot_T-Sport_T116_617_16_057_00.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/\",\"name\":\"Tissot Chrono XL Classic - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Tissot_T-Sport_T116_617_16_057_00.png\",\"datePublished\":\"2018-07-17T17:06:41+00:00\",\"dateModified\":\"2026-06-01T08:16:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Tissot_T-Sport_T116_617_16_057_00.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Tissot_T-Sport_T116_617_16_057_00.png\",\"width\":1000,\"height\":1400,\"caption\":\"Tudor Uhr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/t-sport-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chrono XL Classic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tissot Chrono XL Classic - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/","og_locale":"en_US","og_type":"article","og_title":"Tissot Chrono XL Classic - Galli Uhren Bijouterie","og_description":"Dieser sportliche Chronograph bietet eines der gr\u00f6ssten Geh\u00e4use der gesamten Tissot-Kollektion (45mm). Das kratzfeste Saphirglas sch\u00fctzt das Zifferblatt mit Indizes und arabischen Ziffern, welche eine Superluminova Beschichtung besitzen. Schweizer Technologie zu einem unschlagbaren Preis!","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:16:18+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Tissot_T-Sport_T116_617_16_057_00.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/","name":"Tissot Chrono XL Classic - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Tissot_T-Sport_T116_617_16_057_00.png","datePublished":"2018-07-17T17:06:41+00:00","dateModified":"2026-06-01T08:16:18+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Tissot_T-Sport_T116_617_16_057_00.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Tissot_T-Sport_T116_617_16_057_00.png","width":1000,"height":1400,"caption":"Tudor Uhr"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/t-sport-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Chrono XL Classic"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/535"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=561"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=561"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=561"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}