{"id":51988,"date":"2026-05-19T11:25:43","date_gmt":"2026-05-19T09:25:43","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=51988"},"modified":"2026-05-19T11:29:48","modified_gmt":"2026-05-19T09:29:48","slug":"petite-seconde-violette-34248aa06-bva142","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/","title":{"rendered":"Louis Erard Petite Seconde Violette"},"content":{"rendered":"<p>Die Louis Erard Petite Seconde Violette verbindet klassische Schweizer Uhrmacherkunst mit modernem Design und einer aussergew\u00f6hnlichen Farbgebung. Mit ihrem markanten violetten Zifferblatt setzt diese luxuri\u00f6se Automatikuhr ein stilvolles Statement und hebt sich deutlich von klassischen Dresswatches ab. Die harmonische Kombination aus poliertem Edelstahlgeh\u00e4use, feinen Details und der charakteristischen kleinen Sekunde macht die Petite Seconde Violette zu einer besonderen Wahl f\u00fcr Uhrenliebhaber und Sammler.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Louis Erard Petite Seconde Violette verbindet klassische Schweizer Uhrmacherkunst mit modernem Design und einer aussergew\u00f6hnlichen Farbgebung. Mit ihrem markanten violetten Zifferblatt setzt diese luxuri\u00f6se Automatikuhr ein stilvolles Statement und hebt sich deutlich von klassischen Dresswatches ab. Die harmonische Kombination aus poliertem Edelstahlgeh\u00e4use, feinen Details und der charakteristischen kleinen Sekunde macht die Petite Seconde Violette&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/\" title=\"Read Louis Erard Petite Seconde Violette\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":51829,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-51988","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-louis-erard","uhrenhersteller-noirmont","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Louis Erard Petite Seconde Violette - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Louis Erard Petite Seconde Violette - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Louis Erard Petite Seconde Violette verbindet klassische Schweizer Uhrmacherkunst mit modernem Design und einer aussergew\u00f6hnlichen Farbgebung. Mit ihrem markanten violetten Zifferblatt setzt diese luxuri\u00f6se Automatikuhr ein stilvolles Statement und hebt sich deutlich von klassischen Dresswatches ab. Die harmonische Kombination aus poliertem Edelstahlgeh\u00e4use, feinen Details und der charakteristischen kleinen Sekunde macht die Petite Seconde Violette... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T09:29:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/34248AA06-BVA142.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/\",\"name\":\"Louis Erard Petite Seconde Violette - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/34248AA06-BVA142.png\",\"datePublished\":\"2026-05-19T09:25:43+00:00\",\"dateModified\":\"2026-05-19T09:29:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/34248AA06-BVA142.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/34248AA06-BVA142.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/louis-erard\\\/noirmont\\\/petite-seconde-violette-34248aa06-bva142\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Louis Erard Petite Seconde Violette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Louis Erard Petite Seconde Violette - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/","og_locale":"en_US","og_type":"article","og_title":"Louis Erard Petite Seconde Violette - Galli Uhren Bijouterie","og_description":"Die Louis Erard Petite Seconde Violette verbindet klassische Schweizer Uhrmacherkunst mit modernem Design und einer aussergew\u00f6hnlichen Farbgebung. Mit ihrem markanten violetten Zifferblatt setzt diese luxuri\u00f6se Automatikuhr ein stilvolles Statement und hebt sich deutlich von klassischen Dresswatches ab. Die harmonische Kombination aus poliertem Edelstahlgeh\u00e4use, feinen Details und der charakteristischen kleinen Sekunde macht die Petite Seconde Violette... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-05-19T09:29:48+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/34248AA06-BVA142.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/","url":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/","name":"Louis Erard Petite Seconde Violette - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/34248AA06-BVA142.png","datePublished":"2026-05-19T09:25:43+00:00","dateModified":"2026-05-19T09:29:48+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/34248AA06-BVA142.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/34248AA06-BVA142.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/louis-erard\/noirmont\/petite-seconde-violette-34248aa06-bva142\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Louis Erard Petite Seconde Violette"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/51988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/51829"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=51988"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=51988"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=51988"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=51988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}