{"id":51657,"date":"2026-05-06T09:53:07","date_gmt":"2026-05-06T07:53:07","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=51657"},"modified":"2026-05-19T17:48:18","modified_gmt":"2026-05-19T15:48:18","slug":"ii-b31-40-ab3114101l1a1","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/","title":{"rendered":"Breitling Chronomat II B31 40"},"content":{"rendered":"<p>Die Breitling Chronomat ist eine der beliebtesten Luxusuhren f\u00fcr Herren und Damen und steht f\u00fcr Schweizer Pr\u00e4zision, sportliches Design und h\u00f6chste Qualit\u00e4t.<br \/>\nAusgestattet mit einem COSC-zertifizierten Automatikwerk bietet die Breitling Chronomat maximale Genauigkeit und Zuverl\u00e4ssigkeit im Alltag. Hochwertige Materialien wie Edelstahl, Gold oder Bicolor machen sie zur perfekten Wahl f\u00fcr stilbewusste Uhrenliebhaber.<br \/>\nOb als sportliche Armbanduhr oder elegante Luxusuhr \u2013 die Breitling Chronomat verbindet Funktionalit\u00e4t mit exklusivem Design.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Breitling Chronomat ist eine der beliebtesten Luxusuhren f\u00fcr Herren und Damen und steht f\u00fcr Schweizer Pr\u00e4zision, sportliches Design und h\u00f6chste Qualit\u00e4t. Ausgestattet mit einem COSC-zertifizierten Automatikwerk bietet die Breitling Chronomat maximale Genauigkeit und Zuverl\u00e4ssigkeit im Alltag. Hochwertige Materialien wie Edelstahl, Gold oder Bicolor machen sie zur perfekten Wahl f\u00fcr stilbewusste Uhrenliebhaber. Ob als sportliche&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/\" title=\"Read Breitling Chronomat II B31 40\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":51575,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-51657","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-breitling","uhrenhersteller-chronomat","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Breitling Chronomat II B31 40 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breitling Chronomat II B31 40 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Breitling Chronomat ist eine der beliebtesten Luxusuhren f\u00fcr Herren und Damen und steht f\u00fcr Schweizer Pr\u00e4zision, sportliches Design und h\u00f6chste Qualit\u00e4t. Ausgestattet mit einem COSC-zertifizierten Automatikwerk bietet die Breitling Chronomat maximale Genauigkeit und Zuverl\u00e4ssigkeit im Alltag. Hochwertige Materialien wie Edelstahl, Gold oder Bicolor machen sie zur perfekten Wahl f\u00fcr stilbewusste Uhrenliebhaber. Ob als sportliche... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T15:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/\",\"name\":\"Breitling Chronomat II B31 40 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png\",\"datePublished\":\"2026-05-06T07:53:07+00:00\",\"dateModified\":\"2026-05-19T15:48:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/chronomat\\\/ii-b31-40-ab3114101l1a1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Breitling Chronomat II B31 40\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breitling Chronomat II B31 40 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/","og_locale":"en_US","og_type":"article","og_title":"Breitling Chronomat II B31 40 - Galli Uhren Bijouterie","og_description":"Die Breitling Chronomat ist eine der beliebtesten Luxusuhren f\u00fcr Herren und Damen und steht f\u00fcr Schweizer Pr\u00e4zision, sportliches Design und h\u00f6chste Qualit\u00e4t. Ausgestattet mit einem COSC-zertifizierten Automatikwerk bietet die Breitling Chronomat maximale Genauigkeit und Zuverl\u00e4ssigkeit im Alltag. Hochwertige Materialien wie Edelstahl, Gold oder Bicolor machen sie zur perfekten Wahl f\u00fcr stilbewusste Uhrenliebhaber. Ob als sportliche... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-05-19T15:48:18+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/","url":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/","name":"Breitling Chronomat II B31 40 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png","datePublished":"2026-05-06T07:53:07+00:00","dateModified":"2026-05-19T15:48:18+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Chronomat-B31-Automatic-40_AB3114101L1A1_GreenMetal_RGB.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/chronomat\/ii-b31-40-ab3114101l1a1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Breitling Chronomat II B31 40"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/51657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/51575"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=51657"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=51657"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=51657"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=51657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}