{"id":50395,"date":"2026-03-23T15:43:55","date_gmt":"2026-03-23T14:43:55","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=50395"},"modified":"2026-03-23T15:45:42","modified_gmt":"2026-03-23T14:45:42","slug":"chrono-l-42mm-t116-417-11-042-00","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/","title":{"rendered":"Tissot Chrono L 42mm"},"content":{"rendered":"<p>Die Tissot Chrono L 42mm erg\u00e4nzt die Tissot XL Familie mit einem Durchmesser von 42 Millimetern! Inspiriert von der Chrono XL, ist diese Uhr ideal f\u00fcr alle, die einen sportlichen und eleganten Chronographen mit Schweizer Technologie, modernem Stil und etwas kleineren Geh\u00e4usema\u00dfen suchen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tissot Chrono L 42mm erg\u00e4nzt die Tissot XL Familie mit einem Durchmesser von 42 Millimetern! Inspiriert von der Chrono XL, ist diese Uhr ideal f\u00fcr alle, die einen sportlichen und eleganten Chronographen mit Schweizer Technologie, modernem Stil und etwas kleineren Geh\u00e4usema\u00dfen suchen.<\/p>\n","protected":false},"featured_media":50376,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-50395","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tissot","uhrenhersteller-t-sport","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tissot Chrono L 42mm - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tissot Chrono L 42mm - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Tissot Chrono L 42mm erg\u00e4nzt die Tissot XL Familie mit einem Durchmesser von 42 Millimetern! Inspiriert von der Chrono XL, ist diese Uhr ideal f\u00fcr alle, die einen sportlichen und eleganten Chronographen mit Schweizer Technologie, modernem Stil und etwas kleineren Geh\u00e4usema\u00dfen suchen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T14:45:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/\",\"name\":\"Tissot Chrono L 42mm - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png\",\"datePublished\":\"2026-03-23T14:43:55+00:00\",\"dateModified\":\"2026-03-23T14:45:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/chrono-l-42mm-t116-417-11-042-00\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tissot Chrono L 42mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tissot Chrono L 42mm - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/","og_locale":"en_US","og_type":"article","og_title":"Tissot Chrono L 42mm - Galli Uhren Bijouterie","og_description":"Die Tissot Chrono L 42mm erg\u00e4nzt die Tissot XL Familie mit einem Durchmesser von 42 Millimetern! Inspiriert von der Chrono XL, ist diese Uhr ideal f\u00fcr alle, die einen sportlichen und eleganten Chronographen mit Schweizer Technologie, modernem Stil und etwas kleineren Geh\u00e4usema\u00dfen suchen.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-03-23T14:45:42+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/","name":"Tissot Chrono L 42mm - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png","datePublished":"2026-03-23T14:43:55+00:00","dateModified":"2026-03-23T14:45:42+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/7dd55aaa-b96d-4e44-a21c-3cb5cb74772e_T116-417-11-042-00-1.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/chrono-l-42mm-t116-417-11-042-00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Tissot Chrono L 42mm"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/50395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/50376"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=50395"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=50395"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=50395"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=50395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}