{"id":49623,"date":"2026-02-16T11:06:05","date_gmt":"2026-02-16T10:06:05","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=49623"},"modified":"2026-03-16T10:30:40","modified_gmt":"2026-03-16T09:30:40","slug":"automatic-40-iw358402","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/","title":{"rendered":"IWC Portugieser Automatic 40"},"content":{"rendered":"<p>Die klaren Strukturen der Portugieser Automatic 40 machen sie trotz ihrer kompakten Ausf\u00fchrung zu einem begehrenswerten Uhrenmodell. Neben der aus dem Namen bereits ersichtlichen Automatik-Funktion kehrt IWC Schaffhausen mit dieser Neuheit zu einer bew\u00e4hrten Tradition zur\u00fcck, n\u00e4mlich der Sekundenanzeige auf der 6-Uhr-Position. Bemerkenswert ist dabei die Realisierung auf dem kompakten 40-Millimeter-Format, das die Portugieser Automatic 40 auszeichnet. Das leicht abzulesende und deutlich strukturierte Zifferblatt setzt die seit den 30er-Jahren bekannte Designsprache der Portugieser von IWC gekonnt fort und erg\u00e4nzt sie um ein weiteres zeitloses Schmuckst\u00fcck.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die klaren Strukturen der Portugieser Automatic 40 machen sie trotz ihrer kompakten Ausf\u00fchrung zu einem begehrenswerten Uhrenmodell. Neben der aus dem Namen bereits ersichtlichen Automatik-Funktion kehrt IWC Schaffhausen mit dieser Neuheit zu einer bew\u00e4hrten Tradition zur\u00fcck, n\u00e4mlich der Sekundenanzeige auf der 6-Uhr-Position. Bemerkenswert ist dabei die Realisierung auf dem kompakten 40-Millimeter-Format, das die Portugieser Automatic&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/\" title=\"Read IWC Portugieser Automatic 40\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":49592,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-49623","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-iwc","uhrenhersteller-portugieser","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IWC Portugieser Automatic 40 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IWC Portugieser Automatic 40 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die klaren Strukturen der Portugieser Automatic 40 machen sie trotz ihrer kompakten Ausf\u00fchrung zu einem begehrenswerten Uhrenmodell. Neben der aus dem Namen bereits ersichtlichen Automatik-Funktion kehrt IWC Schaffhausen mit dieser Neuheit zu einer bew\u00e4hrten Tradition zur\u00fcck, n\u00e4mlich der Sekundenanzeige auf der 6-Uhr-Position. Bemerkenswert ist dabei die Realisierung auf dem kompakten 40-Millimeter-Format, das die Portugieser Automatic... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T09:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/\",\"name\":\"IWC Portugieser Automatic 40 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png\",\"datePublished\":\"2026-02-16T10:06:05+00:00\",\"dateModified\":\"2026-03-16T09:30:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/iwc\\\/portugieser\\\/automatic-40-iw358402\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IWC Portugieser Automatic 40\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IWC Portugieser Automatic 40 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/","og_locale":"en_US","og_type":"article","og_title":"IWC Portugieser Automatic 40 - Galli Uhren Bijouterie","og_description":"Die klaren Strukturen der Portugieser Automatic 40 machen sie trotz ihrer kompakten Ausf\u00fchrung zu einem begehrenswerten Uhrenmodell. Neben der aus dem Namen bereits ersichtlichen Automatik-Funktion kehrt IWC Schaffhausen mit dieser Neuheit zu einer bew\u00e4hrten Tradition zur\u00fcck, n\u00e4mlich der Sekundenanzeige auf der 6-Uhr-Position. Bemerkenswert ist dabei die Realisierung auf dem kompakten 40-Millimeter-Format, das die Portugieser Automatic... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-03-16T09:30:40+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/","url":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/","name":"IWC Portugieser Automatic 40 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png","datePublished":"2026-02-16T10:06:05+00:00","dateModified":"2026-03-16T09:30:40+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1d5acb17a7c2fa3563f4d8b0326a656ca4f47892.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/iwc\/portugieser\/automatic-40-iw358402\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"IWC Portugieser Automatic 40"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/49623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/49592"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=49623"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=49623"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=49623"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=49623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}