{"id":45822,"date":"2025-10-20T15:51:53","date_gmt":"2025-10-20T13:51:53","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=45822"},"modified":"2025-10-20T16:08:20","modified_gmt":"2025-10-20T14:08:20","slug":"tudor-black-bay-ceramic-m79210cnu-0001-173","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/galli-cpo\/tudor-2\/tudor-black-bay-ceramic-m79210cnu-0001-173\/","title":{"rendered":"Tudor Black Bay Ceramic"},"content":{"rendered":"<p>Die Black Bay Ceramic mit einem Geh\u00e4usedurchmesser von 41mm ist die erste Uhr von Tudor, welche vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie in Bern (METAS) zertifiziert wurde. Die METAS-Zertifizierung setzt voraus, dass die betreffende Uhr in der Schweiz hergestellt und COSC-zertifiziert ist und ausserdem eine Reihe zus\u00e4tzlicher Tests besteht.<\/p>\n<p>Jahrgang: 2021<\/p>\n<p>Zustand: Sehr Gut<\/p>\n<p>Original Papiere: Ja<\/p>\n<p>Original Box: Ja<\/p>\n<p>Garantie: Bis Juli 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Black Bay Ceramic mit einem Geh\u00e4usedurchmesser von 41mm ist die erste Uhr von Tudor, welche vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie in Bern (METAS) zertifiziert wurde. Die METAS-Zertifizierung setzt voraus, dass die betreffende Uhr in der Schweiz hergestellt und COSC-zertifiziert ist und ausserdem eine Reihe zus\u00e4tzlicher Tests besteht. Jahrgang: 2021 Zustand: Sehr Gut Original Papiere:&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/galli-cpo\/tudor-2\/tudor-black-bay-ceramic-m79210cnu-0001-173\/\" title=\"Read Tudor Black Bay Ceramic\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":45680,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-45822","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-galli-cpo","uhrenhersteller-tudor-2","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tudor Black Bay Ceramic - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tudor Black Bay Ceramic - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Black Bay Ceramic mit einem Geh\u00e4usedurchmesser von 41mm ist die erste Uhr von Tudor, welche vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie in Bern (METAS) zertifiziert wurde. Die METAS-Zertifizierung setzt voraus, dass die betreffende Uhr in der Schweiz hergestellt und COSC-zertifiziert ist und ausserdem eine Reihe zus\u00e4tzlicher Tests besteht. Jahrgang: 2021 Zustand: Sehr Gut Original Papiere:... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-20T14:08:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_2121.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/\",\"name\":\"Tudor Black Bay Ceramic - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/IMG_2121.png\",\"datePublished\":\"2025-10-20T13:51:53+00:00\",\"dateModified\":\"2025-10-20T14:08:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/IMG_2121.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/IMG_2121.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/tudor-black-bay-ceramic-m79210cnu-0001-173\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tudor Black Bay Ceramic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tudor Black Bay Ceramic - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/","og_locale":"en_US","og_type":"article","og_title":"Tudor Black Bay Ceramic - Galli Uhren Bijouterie","og_description":"Die Black Bay Ceramic mit einem Geh\u00e4usedurchmesser von 41mm ist die erste Uhr von Tudor, welche vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie in Bern (METAS) zertifiziert wurde. Die METAS-Zertifizierung setzt voraus, dass die betreffende Uhr in der Schweiz hergestellt und COSC-zertifiziert ist und ausserdem eine Reihe zus\u00e4tzlicher Tests besteht. Jahrgang: 2021 Zustand: Sehr Gut Original Papiere:... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-10-20T14:08:20+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_2121.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/","url":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/","name":"Tudor Black Bay Ceramic - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_2121.png","datePublished":"2025-10-20T13:51:53+00:00","dateModified":"2025-10-20T14:08:20+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_2121.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_2121.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/tudor-black-bay-ceramic-m79210cnu-0001-173\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Tudor Black Bay Ceramic"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/45822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/45680"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=45822"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=45822"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=45822"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=45822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}