{"id":44667,"date":"2025-09-25T16:40:47","date_gmt":"2025-09-25T14:40:47","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=44667"},"modified":"2026-06-01T10:11:31","modified_gmt":"2026-06-01T08:11:31","slug":"ultra-chron-classic-l2-937-4-72-6","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/","title":{"rendered":"Longines Ultra Chron Classic"},"content":{"rendered":"<p>1968 brachte LONGINES die Ultra-Chron Diver auf den Markt, die erste Taucheruhr mit einem Hochfrequenzwerk. Zu dieser Zeit hatte sich LONGINES bereits als Pionier der Hochfrequenztechnologie etabliert.<br \/>\nDie neue Ultra-Chron ist von den \u00e4sthetischen Codes und den professionellen Tauchfunktionen des Modells von 1968 inspiriert. Diese Chronometer-zertifizierten Uhren werden von einem exklusiven LONGINES Kaliber angetrieben, das mit einer Unruhspiralfeder aus Silizium ausgestattet und resistent gegen Magnetfelder ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1968 brachte LONGINES die Ultra-Chron Diver auf den Markt, die erste Taucheruhr mit einem Hochfrequenzwerk. Zu dieser Zeit hatte sich LONGINES bereits als Pionier der Hochfrequenztechnologie etabliert. Die neue Ultra-Chron ist von den \u00e4sthetischen Codes und den professionellen Tauchfunktionen des Modells von 1968 inspiriert. Diese Chronometer-zertifizierten Uhren werden von einem exklusiven LONGINES Kaliber angetrieben, das&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/\" title=\"Read Longines Ultra Chron Classic\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":44647,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-44667","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-longines","uhrenhersteller-watchmaking-tradition","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Longines Ultra Chron Classic - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longines Ultra Chron Classic - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"1968 brachte LONGINES die Ultra-Chron Diver auf den Markt, die erste Taucheruhr mit einem Hochfrequenzwerk. Zu dieser Zeit hatte sich LONGINES bereits als Pionier der Hochfrequenztechnologie etabliert. Die neue Ultra-Chron ist von den \u00e4sthetischen Codes und den professionellen Tauchfunktionen des Modells von 1968 inspiriert. Diese Chronometer-zertifizierten Uhren werden von einem exklusiven LONGINES Kaliber angetrieben, das... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:11:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/\",\"name\":\"Longines Ultra Chron Classic - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png\",\"datePublished\":\"2025-09-25T14:40:47+00:00\",\"dateModified\":\"2026-06-01T08:11:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/watchmaking-tradition\\\/ultra-chron-classic-l2-937-4-72-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Longines Ultra Chron Classic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longines Ultra Chron Classic - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/","og_locale":"en_US","og_type":"article","og_title":"Longines Ultra Chron Classic - Galli Uhren Bijouterie","og_description":"1968 brachte LONGINES die Ultra-Chron Diver auf den Markt, die erste Taucheruhr mit einem Hochfrequenzwerk. Zu dieser Zeit hatte sich LONGINES bereits als Pionier der Hochfrequenztechnologie etabliert. Die neue Ultra-Chron ist von den \u00e4sthetischen Codes und den professionellen Tauchfunktionen des Modells von 1968 inspiriert. Diese Chronometer-zertifizierten Uhren werden von einem exklusiven LONGINES Kaliber angetrieben, das... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:11:31+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/","url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/","name":"Longines Ultra Chron Classic - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png","datePublished":"2025-09-25T14:40:47+00:00","dateModified":"2026-06-01T08:11:31+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-ultra-chron-classic-l2-937-4-72-6-b7f9f2-hero.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/watchmaking-tradition\/ultra-chron-classic-l2-937-4-72-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Longines Ultra Chron Classic"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/44667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/44647"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=44667"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=44667"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=44667"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=44667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}