{"id":44571,"date":"2025-09-23T10:43:43","date_gmt":"2025-09-23T08:43:43","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=44571"},"modified":"2026-06-01T10:16:58","modified_gmt":"2026-06-01T08:16:58","slug":"srv-30mm-t160-110-36-113-00","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/","title":{"rendered":"Tissot SRV 30mm"},"content":{"rendered":"<p>Die SRV-Uhr ist inspiriert von der Art Deco-Zeit, die in den 1920er Jahren entwickelt wurde. Diese Zeit zeichnet sich durch geometrische Formen und abstrakte Muster aus und wurde zu einem dominierenden Stil in der Architektur, Innenarchitektur, Mode und Grafik. W\u00e4hrend die SRV direkt von einem Modell aus dem Jahr 1975 inspiriert ist, war dieses Design selbst eine Neuinterpretation der fr\u00fcheren Kreationen von Tissot aus den 1920er Jahren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die SRV-Uhr ist inspiriert von der Art Deco-Zeit, die in den 1920er Jahren entwickelt wurde. Diese Zeit zeichnet sich durch geometrische Formen und abstrakte Muster aus und wurde zu einem dominierenden Stil in der Architektur, Innenarchitektur, Mode und Grafik. W\u00e4hrend die SRV direkt von einem Modell aus dem Jahr 1975 inspiriert ist, war dieses Design&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/\" title=\"Read Tissot SRV 30mm\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":44466,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-44571","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tissot","uhrenhersteller-t-lady","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tissot SRV 30mm - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tissot SRV 30mm - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die SRV-Uhr ist inspiriert von der Art Deco-Zeit, die in den 1920er Jahren entwickelt wurde. Diese Zeit zeichnet sich durch geometrische Formen und abstrakte Muster aus und wurde zu einem dominierenden Stil in der Architektur, Innenarchitektur, Mode und Grafik. W\u00e4hrend die SRV direkt von einem Modell aus dem Jahr 1975 inspiriert ist, war dieses Design... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:16:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/\",\"name\":\"Tissot SRV 30mm - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png\",\"datePublished\":\"2025-09-23T08:43:43+00:00\",\"dateModified\":\"2026-06-01T08:16:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-lady\\\/srv-30mm-t160-110-36-113-00\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tissot SRV 30mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tissot SRV 30mm - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/","og_locale":"en_US","og_type":"article","og_title":"Tissot SRV 30mm - Galli Uhren Bijouterie","og_description":"Die SRV-Uhr ist inspiriert von der Art Deco-Zeit, die in den 1920er Jahren entwickelt wurde. Diese Zeit zeichnet sich durch geometrische Formen und abstrakte Muster aus und wurde zu einem dominierenden Stil in der Architektur, Innenarchitektur, Mode und Grafik. W\u00e4hrend die SRV direkt von einem Modell aus dem Jahr 1975 inspiriert ist, war dieses Design... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:16:58+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/","name":"Tissot SRV 30mm - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png","datePublished":"2025-09-23T08:43:43+00:00","dateModified":"2026-06-01T08:16:58+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/44e4574f-8cad-4ad0-b447-daf16996ed69_T160-110-36-113-00_Shadow.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-lady\/srv-30mm-t160-110-36-113-00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Tissot SRV 30mm"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/44571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/44466"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=44571"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=44571"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=44571"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=44571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}