{"id":43318,"date":"2025-06-19T11:25:37","date_gmt":"2025-06-19T09:25:37","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=43318"},"modified":"2026-03-02T11:43:21","modified_gmt":"2026-03-02T10:43:21","slug":"aqua-terra-150m-220-20-30-20-02-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/","title":{"rendered":"Omega Seamaster Aqua Terra 150M"},"content":{"rendered":"<p>Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Seine zarten Proportionen hat das schlanke 30-mm-Geh\u00e4use dieser Uhr dem innovativen OMEGA Co-Axial Master Chronometer Kaliber 8751 zu verdanken, das vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie (METAS) nach den h\u00f6chsten Standards der Branche zertifiziert wurde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Seine zarten Proportionen hat das schlanke 30-mm-Geh\u00e4use dieser Uhr dem innovativen OMEGA Co-Axial Master Chronometer Kaliber 8751 zu verdanken, das vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie (METAS) nach den h\u00f6chsten Standards der Branche zertifiziert wurde.<\/p>\n","protected":false},"featured_media":43296,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-43318","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-seamaster","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Seamaster Aqua Terra 150M - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Seamaster Aqua Terra 150M - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Seine zarten Proportionen hat das schlanke 30-mm-Geh\u00e4use dieser Uhr dem innovativen OMEGA Co-Axial Master Chronometer Kaliber 8751 zu verdanken, das vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie (METAS) nach den h\u00f6chsten Standards der Branche zertifiziert wurde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T10:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/\",\"name\":\"Omega Seamaster Aqua Terra 150M - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png\",\"datePublished\":\"2025-06-19T09:25:37+00:00\",\"dateModified\":\"2026-03-02T10:43:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150m-220-20-30-20-02-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Seamaster Aqua Terra 150M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Seamaster Aqua Terra 150M - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Seamaster Aqua Terra 150M - Galli Uhren Bijouterie","og_description":"Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Seine zarten Proportionen hat das schlanke 30-mm-Geh\u00e4use dieser Uhr dem innovativen OMEGA Co-Axial Master Chronometer Kaliber 8751 zu verdanken, das vom Eidgen\u00f6ssischen Institut f\u00fcr Metrologie (METAS) nach den h\u00f6chsten Standards der Branche zertifiziert wurde.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-03-02T10:43:21+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/","name":"Omega Seamaster Aqua Terra 150M - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png","datePublished":"2025-06-19T09:25:37+00:00","dateModified":"2026-03-02T10:43:21+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-30-mm-22020302002001-f670f2.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150m-220-20-30-20-02-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Seamaster Aqua Terra 150M"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/43318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/43296"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=43318"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=43318"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=43318"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=43318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}