{"id":42989,"date":"2025-06-06T15:45:47","date_gmt":"2025-06-06T13:45:47","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=42989"},"modified":"2026-06-01T10:16:21","modified_gmt":"2026-06-01T08:16:21","slug":"seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/","title":{"rendered":"Tissot Seastar 1000 Quartz Chronograph 38mm"},"content":{"rendered":"<p>Der neue 38-mm-Quarz-Chronograph, der aus dem Erbe der Seastar hervorgegangen ist, bringt die charakteristische Identit\u00e4t der Kollektion auf neue Weise zum Ausdruck &#8211; er verleiht jeder Bewegung Pr\u00e4zision und jeder Variation Pers\u00f6nlichkeit. Das 38-mm-Edelstahlgeh\u00e4use ist bis zu 30 bar (300m\/1000ft) wasserdicht und bietet zuverl\u00e4ssige Leistung in einem Format, das zu einer Vielzahl von Handgelenken passt. Sie wird von einem Schweizer Quarz-Chronographenwerk angetrieben und verf\u00fcgt \u00fcber eine Wassersportl\u00fcnette, eine verschraubte Krone und einen verschraubten Geh\u00e4useboden sowie Chronographenzifferbl\u00e4tter f\u00fcr eine pr\u00e4zise Zeitmessung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der neue 38-mm-Quarz-Chronograph, der aus dem Erbe der Seastar hervorgegangen ist, bringt die charakteristische Identit\u00e4t der Kollektion auf neue Weise zum Ausdruck &#8211; er verleiht jeder Bewegung Pr\u00e4zision und jeder Variation Pers\u00f6nlichkeit. Das 38-mm-Edelstahlgeh\u00e4use ist bis zu 30 bar (300m\/1000ft) wasserdicht und bietet zuverl\u00e4ssige Leistung in einem Format, das zu einer Vielzahl von Handgelenken passt&#8230;.  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/\" title=\"Read Tissot Seastar 1000 Quartz Chronograph 38mm\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":42971,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-42989","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tissot","uhrenhersteller-t-sport","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tissot Seastar 1000 Quartz Chronograph 38mm - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tissot Seastar 1000 Quartz Chronograph 38mm - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Der neue 38-mm-Quarz-Chronograph, der aus dem Erbe der Seastar hervorgegangen ist, bringt die charakteristische Identit\u00e4t der Kollektion auf neue Weise zum Ausdruck &#8211; er verleiht jeder Bewegung Pr\u00e4zision und jeder Variation Pers\u00f6nlichkeit. Das 38-mm-Edelstahlgeh\u00e4use ist bis zu 30 bar (300m\/1000ft) wasserdicht und bietet zuverl\u00e4ssige Leistung in einem Format, das zu einer Vielzahl von Handgelenken passt.... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:16:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/T120-217-37-041-00_Shadow.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/\",\"name\":\"Tissot Seastar 1000 Quartz Chronograph 38mm - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/T120-217-37-041-00_Shadow.png\",\"datePublished\":\"2025-06-06T13:45:47+00:00\",\"dateModified\":\"2026-06-01T08:16:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/T120-217-37-041-00_Shadow.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/T120-217-37-041-00_Shadow.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tissot\\\/t-sport\\\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tissot Seastar 1000 Quartz Chronograph 38mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tissot Seastar 1000 Quartz Chronograph 38mm - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/","og_locale":"en_US","og_type":"article","og_title":"Tissot Seastar 1000 Quartz Chronograph 38mm - Galli Uhren Bijouterie","og_description":"Der neue 38-mm-Quarz-Chronograph, der aus dem Erbe der Seastar hervorgegangen ist, bringt die charakteristische Identit\u00e4t der Kollektion auf neue Weise zum Ausdruck &#8211; er verleiht jeder Bewegung Pr\u00e4zision und jeder Variation Pers\u00f6nlichkeit. Das 38-mm-Edelstahlgeh\u00e4use ist bis zu 30 bar (300m\/1000ft) wasserdicht und bietet zuverl\u00e4ssige Leistung in einem Format, das zu einer Vielzahl von Handgelenken passt.... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:16:21+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/T120-217-37-041-00_Shadow.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/","name":"Tissot Seastar 1000 Quartz Chronograph 38mm - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/T120-217-37-041-00_Shadow.png","datePublished":"2025-06-06T13:45:47+00:00","dateModified":"2026-06-01T08:16:21+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/T120-217-37-041-00_Shadow.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/T120-217-37-041-00_Shadow.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tissot\/t-sport\/seastar-1000-quartz-chronograph-38mm-t120-217-37-041-00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Tissot Seastar 1000 Quartz Chronograph 38mm"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/42989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/42971"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=42989"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=42989"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=42989"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=42989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}