{"id":42219,"date":"2025-04-04T10:10:29","date_gmt":"2025-04-04T08:10:29","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=42219"},"modified":"2025-04-05T13:28:39","modified_gmt":"2025-04-05T11:28:39","slug":"automatic-36mm-756007-ss001-330-2","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/","title":{"rendered":"Maurice Lacroix 1975 Automatic 36MM"},"content":{"rendered":"<p>Mit ihrem eleganten Design und den schlanken Proportionen strahlt die Kollektion 1975 einen Hauch von Vintage aus und verspricht gleichzeitig dauerhafte Attraktivit\u00e4t. Die Kollektion 1975 ist zwar neu, aber dennoch mit den gewohnten Maurice Lacroix Merkmalen ausgestattet. Sie ist schlicht, raffiniert und von hohem Wert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit ihrem eleganten Design und den schlanken Proportionen strahlt die Kollektion 1975 einen Hauch von Vintage aus und verspricht gleichzeitig dauerhafte Attraktivit\u00e4t. Die Kollektion 1975 ist zwar neu, aber dennoch mit den gewohnten Maurice Lacroix Merkmalen ausgestattet. Sie ist schlicht, raffiniert und von hohem Wert.<\/p>\n","protected":false},"featured_media":42129,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-42219","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie","uhrenhersteller-maurice-lacroix","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maurice Lacroix 1975 Automatic 36MM - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maurice Lacroix 1975 Automatic 36MM - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Mit ihrem eleganten Design und den schlanken Proportionen strahlt die Kollektion 1975 einen Hauch von Vintage aus und verspricht gleichzeitig dauerhafte Attraktivit\u00e4t. Die Kollektion 1975 ist zwar neu, aber dennoch mit den gewohnten Maurice Lacroix Merkmalen ausgestattet. Sie ist schlicht, raffiniert und von hohem Wert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-05T11:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/756007-SS001-330-2_soldat_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/\",\"name\":\"Maurice Lacroix 1975 Automatic 36MM - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/756007-SS001-330-2_soldat_1.png\",\"datePublished\":\"2025-04-04T08:10:29+00:00\",\"dateModified\":\"2025-04-05T11:28:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/756007-SS001-330-2_soldat_1.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/756007-SS001-330-2_soldat_1.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\\\/automatic-36mm-756007-ss001-330-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maurice Lacroix 1975 Automatic 36MM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maurice Lacroix 1975 Automatic 36MM - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/","og_locale":"en_US","og_type":"article","og_title":"Maurice Lacroix 1975 Automatic 36MM - Galli Uhren Bijouterie","og_description":"Mit ihrem eleganten Design und den schlanken Proportionen strahlt die Kollektion 1975 einen Hauch von Vintage aus und verspricht gleichzeitig dauerhafte Attraktivit\u00e4t. Die Kollektion 1975 ist zwar neu, aber dennoch mit den gewohnten Maurice Lacroix Merkmalen ausgestattet. Sie ist schlicht, raffiniert und von hohem Wert.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-04-05T11:28:39+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/756007-SS001-330-2_soldat_1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/","url":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/","name":"Maurice Lacroix 1975 Automatic 36MM - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/756007-SS001-330-2_soldat_1.png","datePublished":"2025-04-04T08:10:29+00:00","dateModified":"2025-04-05T11:28:39+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/756007-SS001-330-2_soldat_1.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/756007-SS001-330-2_soldat_1.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/maurice-lacroix-uhren-kollektion-1975-galli-uhren-bijouterie\/automatic-36mm-756007-ss001-330-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Maurice Lacroix 1975 Automatic 36MM"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/42219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/42129"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=42219"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=42219"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=42219"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=42219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}