{"id":42173,"date":"2025-04-03T16:12:40","date_gmt":"2025-04-03T14:12:40","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=42173"},"modified":"2026-06-01T10:13:26","modified_gmt":"2026-06-01T08:13:26","slug":"ultra-m2543c1a7nu-0001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/","title":{"rendered":"Tudor Pelagos Ultra"},"content":{"rendered":"<p>Die ultimative Tiefseetaucheruhr von Tudor. Mit einem robusten 43-mm-Titangeh\u00e4use, das Tiefen bis zu 1.000 Metern standh\u00e4lt, definiert die Pelagos Ultra neue Massst\u00e4be.<\/p>\n<p>Die innovative, zweifarbige Leuchtmasse (Blau\/Gr\u00fcn) und das speziell entwickelte Armband gew\u00e4hrleisten maximale Funktionalit\u00e4t in extremen Tiefen. Perfekt f\u00fcr professionelle Taucher und Abenteurer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ultimative Tiefseetaucheruhr von Tudor. Mit einem robusten 43-mm-Titangeh\u00e4use, das Tiefen bis zu 1.000 Metern standh\u00e4lt, definiert die Pelagos Ultra neue Massst\u00e4be. Die innovative, zweifarbige Leuchtmasse (Blau\/Gr\u00fcn) und das speziell entwickelte Armband gew\u00e4hrleisten maximale Funktionalit\u00e4t in extremen Tiefen. Perfekt f\u00fcr professionelle Taucher und Abenteurer.<\/p>\n","protected":false},"featured_media":42077,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-42173","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tudor","uhrenhersteller-pelagos","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tudor Pelagos Ultra - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tudor Pelagos Ultra - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die ultimative Tiefseetaucheruhr von Tudor. Mit einem robusten 43-mm-Titangeh\u00e4use, das Tiefen bis zu 1.000 Metern standh\u00e4lt, definiert die Pelagos Ultra neue Massst\u00e4be. Die innovative, zweifarbige Leuchtmasse (Blau\/Gr\u00fcn) und das speziell entwickelte Armband gew\u00e4hrleisten maximale Funktionalit\u00e4t in extremen Tiefen. Perfekt f\u00fcr professionelle Taucher und Abenteurer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:13:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m2543c1a7nu-0001.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/\",\"name\":\"Tudor Pelagos Ultra - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m2543c1a7nu-0001.png\",\"datePublished\":\"2025-04-03T14:12:40+00:00\",\"dateModified\":\"2026-06-01T08:13:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m2543c1a7nu-0001.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m2543c1a7nu-0001.png\",\"width\":1000,\"height\":1400,\"caption\":\"Tudor Pelagos Ultra Galli Z\u00fcrich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/ultra-m2543c1a7nu-0001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tudor Pelagos Ultra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tudor Pelagos Ultra - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/","og_locale":"en_US","og_type":"article","og_title":"Tudor Pelagos Ultra - Galli Uhren Bijouterie","og_description":"Die ultimative Tiefseetaucheruhr von Tudor. Mit einem robusten 43-mm-Titangeh\u00e4use, das Tiefen bis zu 1.000 Metern standh\u00e4lt, definiert die Pelagos Ultra neue Massst\u00e4be. Die innovative, zweifarbige Leuchtmasse (Blau\/Gr\u00fcn) und das speziell entwickelte Armband gew\u00e4hrleisten maximale Funktionalit\u00e4t in extremen Tiefen. Perfekt f\u00fcr professionelle Taucher und Abenteurer.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:13:26+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m2543c1a7nu-0001.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/","name":"Tudor Pelagos Ultra - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m2543c1a7nu-0001.png","datePublished":"2025-04-03T14:12:40+00:00","dateModified":"2026-06-01T08:13:26+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m2543c1a7nu-0001.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m2543c1a7nu-0001.png","width":1000,"height":1400,"caption":"Tudor Pelagos Ultra Galli Z\u00fcrich"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/ultra-m2543c1a7nu-0001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Tudor Pelagos Ultra"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/42173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/42077"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=42173"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=42173"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=42173"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=42173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}