{"id":41511,"date":"2025-02-10T14:42:34","date_gmt":"2025-02-10T13:42:34","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=41511"},"modified":"2025-08-19T13:32:17","modified_gmt":"2025-08-19T11:32:17","slug":"iwc-porsche-design-chronograph-iw3720","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/galli-cpo\/iwc-2\/iwc-porsche-design-chronograph-iw3720\/","title":{"rendered":"IWC Porsche Design Chronograph"},"content":{"rendered":"<p>Die Zusammenarbeit zwischen IWC und Porsche Design begann in den 1970er Jahren und brachte einige der ikonischsten Zeitmesser der Uhrenwelt hervor. Die Partnerschaft hat sowohl in der Uhrenindustrie als auch in der Welt des Designs einen bleibenden Eindruck hinterlassen und ist bis heute ein Synonym f\u00fcr innovative, funktionale und \u00e4sthetisch ansprechende Zeitmesser.<\/p>\n<p>Jahrgang: ca.2000<\/p>\n<p>Zustand: Gut<\/p>\n<p>Original Papiere: Nein<\/p>\n<p>Original Box: Nein<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zusammenarbeit zwischen IWC und Porsche Design begann in den 1970er Jahren und brachte einige der ikonischsten Zeitmesser der Uhrenwelt hervor. Die Partnerschaft hat sowohl in der Uhrenindustrie als auch in der Welt des Designs einen bleibenden Eindruck hinterlassen und ist bis heute ein Synonym f\u00fcr innovative, funktionale und \u00e4sthetisch ansprechende Zeitmesser. Jahrgang: ca.2000 Zustand:&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/galli-cpo\/iwc-2\/iwc-porsche-design-chronograph-iw3720\/\" title=\"Read IWC Porsche Design Chronograph\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":41485,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-41511","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-galli-cpo","uhrenhersteller-iwc-2","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IWC Porsche Design Chronograph - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IWC Porsche Design Chronograph - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Zusammenarbeit zwischen IWC und Porsche Design begann in den 1970er Jahren und brachte einige der ikonischsten Zeitmesser der Uhrenwelt hervor. Die Partnerschaft hat sowohl in der Uhrenindustrie als auch in der Welt des Designs einen bleibenden Eindruck hinterlassen und ist bis heute ein Synonym f\u00fcr innovative, funktionale und \u00e4sthetisch ansprechende Zeitmesser. Jahrgang: ca.2000 Zustand:... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T11:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_3650.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/\",\"name\":\"IWC Porsche Design Chronograph - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/IMG_3650.png\",\"datePublished\":\"2025-02-10T13:42:34+00:00\",\"dateModified\":\"2025-08-19T11:32:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/IMG_3650.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/IMG_3650.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/galli-cpo\\\/iwc-porsche-design-chronograph-iw3720\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IWC Porsche Design Chronograph\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IWC Porsche Design Chronograph - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/","og_locale":"en_US","og_type":"article","og_title":"IWC Porsche Design Chronograph - Galli Uhren Bijouterie","og_description":"Die Zusammenarbeit zwischen IWC und Porsche Design begann in den 1970er Jahren und brachte einige der ikonischsten Zeitmesser der Uhrenwelt hervor. Die Partnerschaft hat sowohl in der Uhrenindustrie als auch in der Welt des Designs einen bleibenden Eindruck hinterlassen und ist bis heute ein Synonym f\u00fcr innovative, funktionale und \u00e4sthetisch ansprechende Zeitmesser. Jahrgang: ca.2000 Zustand:... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-08-19T11:32:17+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_3650.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/","url":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/","name":"IWC Porsche Design Chronograph - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_3650.png","datePublished":"2025-02-10T13:42:34+00:00","dateModified":"2025-08-19T11:32:17+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_3650.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/IMG_3650.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/galli-cpo\/iwc-porsche-design-chronograph-iw3720\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"IWC Porsche Design Chronograph"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/41511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/41485"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=41511"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=41511"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=41511"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=41511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}