{"id":38536,"date":"2024-11-25T16:27:05","date_gmt":"2024-11-25T15:27:05","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=38536"},"modified":"2025-10-25T13:08:50","modified_gmt":"2025-10-25T11:08:50","slug":"anhaenger-weissgold-569-brill-2-74ct-3062-01-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/","title":{"rendered":"Anh\u00e4nger Weissgold 569 Brill. 2.74ct"},"content":{"rendered":"<p>Diamanten werden seit Jahrhunderten von Menschen auf der ganzen Welt gesch\u00e4tzt. Sie gelten als Symbole f\u00fcr Sch\u00f6nheit, Reichtum und Macht. Es ist nicht nur die Tatsache, dass sie aus dem h\u00e4rtesten Material der Erde bestehen. Es ist auch die Tatsache, dass jeder Diamant seine eigenen einzigartigen Eigenschaften hat. Die Farbe, der Schliff und die Einschl\u00fcsse eines Diamanten sind einzigartig und machen ihn zu einem Unikat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diamanten werden seit Jahrhunderten von Menschen auf der ganzen Welt gesch\u00e4tzt. Sie gelten als Symbole f\u00fcr Sch\u00f6nheit, Reichtum und Macht. Es ist nicht nur die Tatsache, dass sie aus dem h\u00e4rtesten Material der Erde bestehen. Es ist auch die Tatsache, dass jeder Diamant seine eigenen einzigartigen Eigenschaften hat. Die Farbe, der Schliff und die Einschl\u00fcsse&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/\" title=\"Read Anh\u00e4nger Weissgold 569 Brill. 2.74ct\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":38507,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[189],"product_tag":[],"class_list":["post-38536","product","type-product","status-publish","has-post-thumbnail","schmuckhersteller-galli-jewelry","schmuckthemen-necklaces","product_cat-schmuck","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anh\u00e4nger Weissgold 569 Brill. 2.74ct - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anh\u00e4nger Weissgold 569 Brill. 2.74ct - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Diamanten werden seit Jahrhunderten von Menschen auf der ganzen Welt gesch\u00e4tzt. Sie gelten als Symbole f\u00fcr Sch\u00f6nheit, Reichtum und Macht. Es ist nicht nur die Tatsache, dass sie aus dem h\u00e4rtesten Material der Erde bestehen. Es ist auch die Tatsache, dass jeder Diamant seine eigenen einzigartigen Eigenschaften hat. Die Farbe, der Schliff und die Einschl\u00fcsse... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-25T11:08:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/High-Society-Ahaenger_3062-01-001.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/\",\"name\":\"Anh\u00e4nger Weissgold 569 Brill. 2.74ct - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/High-Society-Ahaenger_3062-01-001.png\",\"datePublished\":\"2024-11-25T15:27:05+00:00\",\"dateModified\":\"2025-10-25T11:08:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/High-Society-Ahaenger_3062-01-001.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/High-Society-Ahaenger_3062-01-001.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/galli-jewelry\\\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anh\u00e4nger Weissgold 569 Brill. 2.74ct\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anh\u00e4nger Weissgold 569 Brill. 2.74ct - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/","og_locale":"en_US","og_type":"article","og_title":"Anh\u00e4nger Weissgold 569 Brill. 2.74ct - Galli Uhren Bijouterie","og_description":"Diamanten werden seit Jahrhunderten von Menschen auf der ganzen Welt gesch\u00e4tzt. Sie gelten als Symbole f\u00fcr Sch\u00f6nheit, Reichtum und Macht. Es ist nicht nur die Tatsache, dass sie aus dem h\u00e4rtesten Material der Erde bestehen. Es ist auch die Tatsache, dass jeder Diamant seine eigenen einzigartigen Eigenschaften hat. Die Farbe, der Schliff und die Einschl\u00fcsse... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-10-25T11:08:50+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/High-Society-Ahaenger_3062-01-001.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/","url":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/","name":"Anh\u00e4nger Weissgold 569 Brill. 2.74ct - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/High-Society-Ahaenger_3062-01-001.png","datePublished":"2024-11-25T15:27:05+00:00","dateModified":"2025-10-25T11:08:50+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/High-Society-Ahaenger_3062-01-001.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/High-Society-Ahaenger_3062-01-001.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/schmuck\/galli-jewelry\/anhaenger-weissgold-569-brill-2-74ct-3062-01-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Anh\u00e4nger Weissgold 569 Brill. 2.74ct"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/38536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/38507"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=38536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=38536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=38536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=38536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}