{"id":34784,"date":"2024-10-24T11:46:58","date_gmt":"2024-10-24T09:46:58","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=34784"},"modified":"2025-03-13T13:45:50","modified_gmt":"2025-03-13T12:45:50","slug":"super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/","title":{"rendered":"Breitling Super Avenger B01 Chronograph 46 Night Mission"},"content":{"rendered":"<p>Die Avenger ist f\u00fcr Jetpiloten konstruiert und eine Uhr, die es mit den h\u00e4rtesten Bedingungen im Cockpit aufnehmen kann. Aber man braucht nicht in der Luftwaffe zu sein, um ihr k\u00fchnes Design, ihre aussergew\u00f6hnliche Widerstandsf\u00e4higkeit und ihre \u00fcberragende Funktionalit\u00e4t zu sch\u00e4tzen. Performance trifft auf modernes Luftfahrtdesign.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Avenger ist f\u00fcr Jetpiloten konstruiert und eine Uhr, die es mit den h\u00e4rtesten Bedingungen im Cockpit aufnehmen kann. Aber man braucht nicht in der Luftwaffe zu sein, um ihr k\u00fchnes Design, ihre aussergew\u00f6hnliche Widerstandsf\u00e4higkeit und ihre \u00fcberragende Funktionalit\u00e4t zu sch\u00e4tzen. Performance trifft auf modernes Luftfahrtdesign.<\/p>\n","protected":false},"featured_media":34722,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-34784","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-breitling","uhrenhersteller-avenger","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Breitling Super Avenger B01 Chronograph 46 Night Mission - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breitling Super Avenger B01 Chronograph 46 Night Mission - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Avenger ist f\u00fcr Jetpiloten konstruiert und eine Uhr, die es mit den h\u00e4rtesten Bedingungen im Cockpit aufnehmen kann. Aber man braucht nicht in der Luftwaffe zu sein, um ihr k\u00fchnes Design, ihre aussergew\u00f6hnliche Widerstandsf\u00e4higkeit und ihre \u00fcberragende Funktionalit\u00e4t zu sch\u00e4tzen. Performance trifft auf modernes Luftfahrtdesign.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T12:45:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/\",\"name\":\"Breitling Super Avenger B01 Chronograph 46 Night Mission - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png\",\"datePublished\":\"2024-10-24T09:46:58+00:00\",\"dateModified\":\"2025-03-13T12:45:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/avenger\\\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Super Avenger B01 Chronograph 46 Night Mission\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breitling Super Avenger B01 Chronograph 46 Night Mission - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/","og_locale":"en_US","og_type":"article","og_title":"Breitling Super Avenger B01 Chronograph 46 Night Mission - Galli Uhren Bijouterie","og_description":"Die Avenger ist f\u00fcr Jetpiloten konstruiert und eine Uhr, die es mit den h\u00e4rtesten Bedingungen im Cockpit aufnehmen kann. Aber man braucht nicht in der Luftwaffe zu sein, um ihr k\u00fchnes Design, ihre aussergew\u00f6hnliche Widerstandsf\u00e4higkeit und ihre \u00fcberragende Funktionalit\u00e4t zu sch\u00e4tzen. Performance trifft auf modernes Luftfahrtdesign.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-03-13T12:45:50+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/","url":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/","name":"Breitling Super Avenger B01 Chronograph 46 Night Mission - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png","datePublished":"2024-10-24T09:46:58+00:00","dateModified":"2025-03-13T12:45:50+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/sb0148101b1x1-soldier_c6360a05_thumbnail_2048.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/avenger\/super-avenger-b01-chronograph-46-night-mission-sb0148101b1x1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Super Avenger B01 Chronograph 46 Night Mission"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/34784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/34722"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=34784"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=34784"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=34784"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=34784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}