{"id":32240,"date":"2024-06-25T10:55:59","date_gmt":"2024-06-25T08:55:59","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=32240"},"modified":"2025-10-23T15:53:36","modified_gmt":"2025-10-23T13:53:36","slug":"aqua-terra-150-m-220-10-34-20-01-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/","title":{"rendered":"Omega Aqua Terra Master Chronometer 34"},"content":{"rendered":"<p>Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Dieses 34-mm-Modell besitzt ein symmetrisches Edelstahlgeh\u00e4use, dessen verschraubter Geh\u00e4useboden mit einem Wellendesign versehen ist.<\/p>\n<p>Das schwarz lackierte Zifferblatt weist ein diamantpoliertes OMEGA Logo aus Wei\u00dfgold und ein Datumsfenster bei 6 Uhr auf. Die Zeiger und die bootsrumpff\u00f6rmigen Stundenindizes, ebenfalls aus diamantpoliertem Wei\u00dfgold, sind mit wei\u00dfer Super-LumiNova gef\u00fcllt, die im Dunkeln blau leuchtet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Dieses 34-mm-Modell besitzt ein symmetrisches Edelstahlgeh\u00e4use, dessen verschraubter Geh\u00e4useboden mit einem Wellendesign versehen ist. Das schwarz lackierte Zifferblatt weist ein diamantpoliertes OMEGA Logo aus Wei\u00dfgold und ein Datumsfenster bei 6 Uhr auf. Die Zeiger und die bootsrumpff\u00f6rmigen Stundenindizes, ebenfalls aus diamantpoliertem Wei\u00dfgold, sind&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/\" title=\"Read Omega Aqua Terra Master Chronometer 34\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":32230,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-32240","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-seamaster","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Aqua Terra Master Chronometer 34 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Aqua Terra Master Chronometer 34 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Dieses 34-mm-Modell besitzt ein symmetrisches Edelstahlgeh\u00e4use, dessen verschraubter Geh\u00e4useboden mit einem Wellendesign versehen ist. Das schwarz lackierte Zifferblatt weist ein diamantpoliertes OMEGA Logo aus Wei\u00dfgold und ein Datumsfenster bei 6 Uhr auf. Die Zeiger und die bootsrumpff\u00f6rmigen Stundenindizes, ebenfalls aus diamantpoliertem Wei\u00dfgold, sind... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T13:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/\",\"name\":\"Omega Aqua Terra Master Chronometer 34 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png\",\"datePublished\":\"2024-06-25T08:55:59+00:00\",\"dateModified\":\"2025-10-23T13:53:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/seamaster\\\/aqua-terra-150-m-220-10-34-20-01-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Aqua Terra Master Chronometer 34\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Aqua Terra Master Chronometer 34 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Aqua Terra Master Chronometer 34 - Galli Uhren Bijouterie","og_description":"Die Seamaster Aqua Terra ist eine Hommage an OMEGAs gro\u00dfes maritimes Erbe. Dieses 34-mm-Modell besitzt ein symmetrisches Edelstahlgeh\u00e4use, dessen verschraubter Geh\u00e4useboden mit einem Wellendesign versehen ist. Das schwarz lackierte Zifferblatt weist ein diamantpoliertes OMEGA Logo aus Wei\u00dfgold und ein Datumsfenster bei 6 Uhr auf. Die Zeiger und die bootsrumpff\u00f6rmigen Stundenindizes, ebenfalls aus diamantpoliertem Wei\u00dfgold, sind... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-10-23T13:53:36+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/","name":"Omega Aqua Terra Master Chronometer 34 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png","datePublished":"2024-06-25T08:55:59+00:00","dateModified":"2025-10-23T13:53:36+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-seamaster-aqua-terra-150m-co-axial-master-chronometer-34-mm-22010342001001-8bd763.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/seamaster\/aqua-terra-150-m-220-10-34-20-01-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Aqua Terra Master Chronometer 34"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/32240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/32230"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=32240"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=32240"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=32240"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=32240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}