{"id":31992,"date":"2024-06-13T09:31:46","date_gmt":"2024-06-13T07:31:46","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=31992"},"modified":"2026-06-01T10:11:32","modified_gmt":"2026-06-01T08:11:32","slug":"conquest-l3-320-4-07-6","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/","title":{"rendered":"Longines Conquest 30"},"content":{"rendered":"<p>Ohne dabei Eleganz aufzugeben erh\u00e4lt die Conquest Linie den Eroberungsgeist all derer aufrecht, die es gewagt haben, auf der Suche nach neuen Horizonten weiter zu gehen als andere. Der gleiche Geist steckt seit 1954 hinter den Modellen der Conquest Kollektion. Jede Uhr enth\u00e4lt eine subtile Kombination von Leistung und Eleganz, einschlie\u00dflich der anspruchsvollsten technischen Funktionen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ohne dabei Eleganz aufzugeben erh\u00e4lt die Conquest Linie den Eroberungsgeist all derer aufrecht, die es gewagt haben, auf der Suche nach neuen Horizonten weiter zu gehen als andere. Der gleiche Geist steckt seit 1954 hinter den Modellen der Conquest Kollektion. Jede Uhr enth\u00e4lt eine subtile Kombination von Leistung und Eleganz, einschlie\u00dflich der anspruchsvollsten technischen Funktionen.<\/p>\n","protected":false},"featured_media":31937,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-31992","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-longines","uhrenhersteller-performance","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Longines Conquest 30 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longines Conquest 30 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Ohne dabei Eleganz aufzugeben erh\u00e4lt die Conquest Linie den Eroberungsgeist all derer aufrecht, die es gewagt haben, auf der Suche nach neuen Horizonten weiter zu gehen als andere. Der gleiche Geist steckt seit 1954 hinter den Modellen der Conquest Kollektion. Jede Uhr enth\u00e4lt eine subtile Kombination von Leistung und Eleganz, einschlie\u00dflich der anspruchsvollsten technischen Funktionen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:11:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/L3-320-4-07-6_SOL.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/\",\"name\":\"Longines Conquest 30 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/L3-320-4-07-6_SOL.png\",\"datePublished\":\"2024-06-13T07:31:46+00:00\",\"dateModified\":\"2026-06-01T08:11:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/L3-320-4-07-6_SOL.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/L3-320-4-07-6_SOL.png\",\"width\":1000,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/performance\\\/conquest-l3-320-4-07-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conquest 30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longines Conquest 30 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/","og_locale":"en_US","og_type":"article","og_title":"Longines Conquest 30 - Galli Uhren Bijouterie","og_description":"Ohne dabei Eleganz aufzugeben erh\u00e4lt die Conquest Linie den Eroberungsgeist all derer aufrecht, die es gewagt haben, auf der Suche nach neuen Horizonten weiter zu gehen als andere. Der gleiche Geist steckt seit 1954 hinter den Modellen der Conquest Kollektion. Jede Uhr enth\u00e4lt eine subtile Kombination von Leistung und Eleganz, einschlie\u00dflich der anspruchsvollsten technischen Funktionen.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:11:32+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/L3-320-4-07-6_SOL.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/","url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/","name":"Longines Conquest 30 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/L3-320-4-07-6_SOL.png","datePublished":"2024-06-13T07:31:46+00:00","dateModified":"2026-06-01T08:11:32+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/L3-320-4-07-6_SOL.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/L3-320-4-07-6_SOL.png","width":1000,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/performance\/conquest-l3-320-4-07-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Conquest 30"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/31992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/31937"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=31992"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=31992"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=31992"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=31992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}