{"id":2349,"date":"2018-08-20T14:06:17","date_gmt":"2018-08-20T14:06:17","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=schmuck&#038;p=2349"},"modified":"2025-03-13T13:44:07","modified_gmt":"2025-03-13T12:44:07","slug":"odenwald_schmuck_42561_200-3","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/","title":{"rendered":"Odenwald Melody Ring Gelbgold"},"content":{"rendered":"<p>Seit 1882 fertigt Odenwald in ihrer traditionellen Manufaktur hochwertigen Goldschmuck aus der Goldstadt Pforzheim. Von Generation zu Generation wurden die Werte Handarbeit, Kreativit\u00e4t und Individualit\u00e4t weitergegeben. Diese Tradition und die Begeisterung f\u00fcr wertvollen, besonderen Schmuck lassen uns f\u00fcr Sie immer wieder neue Ideen schaffen.<\/p>\n<p>Wie bei anderen Saphirkollektionen kann die Farbauswahl der Steine individuell vom Kunden bestimmt werden. Jede Anfertigung erz\u00e4hlt eine Geschichte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit 1882 fertigt Odenwald in ihrer traditionellen Manufaktur hochwertigen Goldschmuck aus der Goldstadt Pforzheim. Von Generation zu Generation wurden die Werte Handarbeit, Kreativit\u00e4t und Individualit\u00e4t weitergegeben. Diese Tradition und die Begeisterung f\u00fcr wertvollen, besonderen Schmuck lassen uns f\u00fcr Sie immer wieder neue Ideen schaffen. Wie bei anderen Saphirkollektionen kann die Farbauswahl der Steine individuell vom&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/\" title=\"Read Odenwald Melody Ring Gelbgold\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":2310,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[189],"product_tag":[],"class_list":["post-2349","product","type-product","status-publish","has-post-thumbnail","schmuckhersteller-odenwald","schmuckthemen-rings","product_cat-schmuck","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Odenwald Melody Ring Gelbgold - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Odenwald Melody Ring Gelbgold - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Seit 1882 fertigt Odenwald in ihrer traditionellen Manufaktur hochwertigen Goldschmuck aus der Goldstadt Pforzheim. Von Generation zu Generation wurden die Werte Handarbeit, Kreativit\u00e4t und Individualit\u00e4t weitergegeben. Diese Tradition und die Begeisterung f\u00fcr wertvollen, besonderen Schmuck lassen uns f\u00fcr Sie immer wieder neue Ideen schaffen. Wie bei anderen Saphirkollektionen kann die Farbauswahl der Steine individuell vom... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T12:44:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Odenwald_Schmuck_42561_200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/\",\"name\":\"Odenwald Melody Ring Gelbgold - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Odenwald_Schmuck_42561_200.png\",\"datePublished\":\"2018-08-20T14:06:17+00:00\",\"dateModified\":\"2025-03-13T12:44:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Odenwald_Schmuck_42561_200.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Odenwald_Schmuck_42561_200.png\",\"width\":500,\"height\":700,\"caption\":\"Odenwald Edelsteinring\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/odenwald\\\/odenwald_schmuck_42561_200-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Melody Ring Gelbgold\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Odenwald Melody Ring Gelbgold - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/","og_locale":"en_US","og_type":"article","og_title":"Odenwald Melody Ring Gelbgold - Galli Uhren Bijouterie","og_description":"Seit 1882 fertigt Odenwald in ihrer traditionellen Manufaktur hochwertigen Goldschmuck aus der Goldstadt Pforzheim. Von Generation zu Generation wurden die Werte Handarbeit, Kreativit\u00e4t und Individualit\u00e4t weitergegeben. Diese Tradition und die Begeisterung f\u00fcr wertvollen, besonderen Schmuck lassen uns f\u00fcr Sie immer wieder neue Ideen schaffen. Wie bei anderen Saphirkollektionen kann die Farbauswahl der Steine individuell vom... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-03-13T12:44:07+00:00","og_image":[{"width":500,"height":700,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Odenwald_Schmuck_42561_200.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/","url":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/","name":"Odenwald Melody Ring Gelbgold - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Odenwald_Schmuck_42561_200.png","datePublished":"2018-08-20T14:06:17+00:00","dateModified":"2025-03-13T12:44:07+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Odenwald_Schmuck_42561_200.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Odenwald_Schmuck_42561_200.png","width":500,"height":700,"caption":"Odenwald Edelsteinring"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/schmuck\/odenwald\/odenwald_schmuck_42561_200-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Melody Ring Gelbgold"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/2349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=2349"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=2349"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=2349"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=2349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}