{"id":23314,"date":"2024-01-27T12:32:40","date_gmt":"2024-01-27T11:32:40","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=23314"},"modified":"2026-06-01T10:11:16","modified_gmt":"2026-06-01T08:11:16","slug":"conquest-heritage-central-power-reserve-l1-648-4-62-2","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/longines\/watchmaking-tradition\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/","title":{"rendered":"Longines Conquest Heritage Central Power Reserve"},"content":{"rendered":"<p>Longines pr\u00e4sentiert die neue Conquest Heritage in einem Geh\u00e4use mit 38 mm Durchmesser. Mechanisches Uhrwerk mit automatischem Aufzug, das exklusive Longines-Kaliber L896.5 zeigt seine Gangreserve auf rotierenden Scheiben in der Mitte des Zifferblatts an.<\/p>\n<p>Ein ikonisches Modell mit anthrazitfarbenem Zifferblatt und integriertem schwarzen Alligatorlederarmband anl\u00e4sslich des 70-j\u00e4hrigen Jubil\u00e4ums der Kollektion Conquest.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Longines pr\u00e4sentiert die neue Conquest Heritage in einem Geh\u00e4use mit 38 mm Durchmesser. Mechanisches Uhrwerk mit automatischem Aufzug, das exklusive Longines-Kaliber L896.5 zeigt seine Gangreserve auf rotierenden Scheiben in der Mitte des Zifferblatts an. Ein ikonisches Modell mit anthrazitfarbenem Zifferblatt und integriertem schwarzen Alligatorlederarmband anl\u00e4sslich des 70-j\u00e4hrigen Jubil\u00e4ums der Kollektion Conquest.<\/p>\n","protected":false},"featured_media":23257,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-23314","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-longines","uhrenhersteller-watchmaking-tradition","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Longines Conquest Heritage Central Power Reserve - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longines Conquest Heritage Central Power Reserve - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Longines pr\u00e4sentiert die neue Conquest Heritage in einem Geh\u00e4use mit 38 mm Durchmesser. Mechanisches Uhrwerk mit automatischem Aufzug, das exklusive Longines-Kaliber L896.5 zeigt seine Gangreserve auf rotierenden Scheiben in der Mitte des Zifferblatts an. Ein ikonisches Modell mit anthrazitfarbenem Zifferblatt und integriertem schwarzen Alligatorlederarmband anl\u00e4sslich des 70-j\u00e4hrigen Jubil\u00e4ums der Kollektion Conquest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:11:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/\",\"name\":\"Longines Conquest Heritage Central Power Reserve - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png\",\"datePublished\":\"2024-01-27T11:32:40+00:00\",\"dateModified\":\"2026-06-01T08:11:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png\",\"width\":1000,\"height\":1400,\"caption\":\"longines-heritage-central-power-reserve\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/avigation\\\/conquest-heritage-central-power-reserve-l1-648-4-62-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conquest Heritage Central Power Reserve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longines Conquest Heritage Central Power Reserve - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/","og_locale":"en_US","og_type":"article","og_title":"Longines Conquest Heritage Central Power Reserve - Galli Uhren Bijouterie","og_description":"Longines pr\u00e4sentiert die neue Conquest Heritage in einem Geh\u00e4use mit 38 mm Durchmesser. Mechanisches Uhrwerk mit automatischem Aufzug, das exklusive Longines-Kaliber L896.5 zeigt seine Gangreserve auf rotierenden Scheiben in der Mitte des Zifferblatts an. Ein ikonisches Modell mit anthrazitfarbenem Zifferblatt und integriertem schwarzen Alligatorlederarmband anl\u00e4sslich des 70-j\u00e4hrigen Jubil\u00e4ums der Kollektion Conquest.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:11:16+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/","url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/","name":"Longines Conquest Heritage Central Power Reserve - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png","datePublished":"2024-01-27T11:32:40+00:00","dateModified":"2026-06-01T08:11:16+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-conquest-heritage-l1-648-4-62-2-1700782212.png","width":1000,"height":1400,"caption":"longines-heritage-central-power-reserve"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/avigation\/conquest-heritage-central-power-reserve-l1-648-4-62-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Conquest Heritage Central Power Reserve"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/23314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/23257"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=23314"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=23314"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=23314"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=23314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}