{"id":22237,"date":"2023-11-20T16:11:16","date_gmt":"2023-11-20T15:11:16","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=22237"},"modified":"2025-03-13T13:45:24","modified_gmt":"2025-03-13T12:45:24","slug":"legend-diver-39-l3-764-4-90-2","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/","title":{"rendered":"Longines Legend Diver 39"},"content":{"rendered":"<p>Die Uhr ist sofort erkennbar an den beiden Kronen und der inneren drehbaren L\u00fcnette. Die Longines Legend Diver taucht mit einem Durchmesser von 39 mm wieder auf, getreu dem Originalmodell von 1959, von dem sie inspiriert wurde.<\/p>\n<p>Das Uhrwerk hat eine Gangreserve von bis zu 72 Stunden und ist COSC zertifiziert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Uhr ist sofort erkennbar an den beiden Kronen und der inneren drehbaren L\u00fcnette. Die Longines Legend Diver taucht mit einem Durchmesser von 39 mm wieder auf, getreu dem Originalmodell von 1959, von dem sie inspiriert wurde. Das Uhrwerk hat eine Gangreserve von bis zu 72 Stunden und ist COSC zertifiziert.<\/p>\n","protected":false},"featured_media":22183,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-22237","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-longines","uhrenhersteller-diving","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Longines Legend Diver 39 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Longines Legend Diver 39 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Uhr ist sofort erkennbar an den beiden Kronen und der inneren drehbaren L\u00fcnette. Die Longines Legend Diver taucht mit einem Durchmesser von 39 mm wieder auf, getreu dem Originalmodell von 1959, von dem sie inspiriert wurde. Das Uhrwerk hat eine Gangreserve von bis zu 72 Stunden und ist COSC zertifiziert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T12:45:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/\",\"name\":\"Longines Legend Diver 39 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png\",\"datePublished\":\"2023-11-20T15:11:16+00:00\",\"dateModified\":\"2025-03-13T12:45:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png\",\"width\":1000,\"height\":1400,\"caption\":\"longines-legend-diver-blau-galli-zurich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/longines\\\/diving\\\/legend-diver-39-l3-764-4-90-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Legend Diver 39\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Longines Legend Diver 39 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/","og_locale":"en_US","og_type":"article","og_title":"Longines Legend Diver 39 - Galli Uhren Bijouterie","og_description":"Die Uhr ist sofort erkennbar an den beiden Kronen und der inneren drehbaren L\u00fcnette. Die Longines Legend Diver taucht mit einem Durchmesser von 39 mm wieder auf, getreu dem Originalmodell von 1959, von dem sie inspiriert wurde. Das Uhrwerk hat eine Gangreserve von bis zu 72 Stunden und ist COSC zertifiziert.","og_url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-03-13T12:45:24+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/","url":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/","name":"Longines Legend Diver 39 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png","datePublished":"2023-11-20T15:11:16+00:00","dateModified":"2025-03-13T12:45:24+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/watch-collection-longines-legend-diver-l3-764-4-90-2-1698952569.png","width":1000,"height":1400,"caption":"longines-legend-diver-blau-galli-zurich"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/longines\/diving\/legend-diver-39-l3-764-4-90-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Legend Diver 39"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/22237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/22183"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=22237"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=22237"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=22237"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=22237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}