{"id":22015,"date":"2023-11-10T00:27:17","date_gmt":"2023-11-09T23:27:17","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=22015"},"modified":"2026-01-23T15:59:58","modified_gmt":"2026-01-23T14:59:58","slug":"bamboo-over-cuff-1b05897b1t180","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/","title":{"rendered":"Chimento Bamboo Over Cuff"},"content":{"rendered":"<div class=\"ql-block\" data-block-id=\"block-51c8584f-020b-422c-b74d-2b5eeb672326\">CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen.<\/div>\n<div class=\"ql-block\" data-block-id=\"block-a8cad885-79a6-4b80-a60d-ada01f97a2c4\"><\/div>\n<div class=\"ql-block\" data-block-id=\"block-de83b467-9e0c-4d66-86ab-a4262260e70f\">Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer Goldschmiedequalit\u00e4t und Botschafter des italienischen Schmucks in der ganzen Welt werden liessen.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen. Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/\" title=\"Read Chimento Bamboo Over Cuff\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":21328,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[189],"product_tag":[],"class_list":["post-22015","product","type-product","status-publish","has-post-thumbnail","schmuckhersteller-chimento","schmuckthemen-bracelets","product_cat-schmuck","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chimento Bamboo Over Cuff - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chimento Bamboo Over Cuff - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen. Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T14:59:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1B05897B1T.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/\",\"name\":\"Chimento Bamboo Over Cuff - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1B05897B1T.png\",\"datePublished\":\"2023-11-09T23:27:17+00:00\",\"dateModified\":\"2026-01-23T14:59:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1B05897B1T.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1B05897B1T.png\",\"width\":1000,\"height\":1400,\"caption\":\"Chimento-Bamboo Over Cuff-zurich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/bamboo-over-cuff-1b05897b1t180\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chimento Bamboo Over Cuff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chimento Bamboo Over Cuff - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/","og_locale":"en_US","og_type":"article","og_title":"Chimento Bamboo Over Cuff - Galli Uhren Bijouterie","og_description":"CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen. Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-01-23T14:59:58+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1B05897B1T.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/","url":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/","name":"Chimento Bamboo Over Cuff - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1B05897B1T.png","datePublished":"2023-11-09T23:27:17+00:00","dateModified":"2026-01-23T14:59:58+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1B05897B1T.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1B05897B1T.png","width":1000,"height":1400,"caption":"Chimento-Bamboo Over Cuff-zurich"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/bamboo-over-cuff-1b05897b1t180\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Chimento Bamboo Over Cuff"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/22015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/21328"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=22015"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=22015"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=22015"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=22015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}