{"id":21973,"date":"2023-11-08T21:46:56","date_gmt":"2023-11-08T20:46:56","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=21973"},"modified":"2026-01-23T15:45:33","modified_gmt":"2026-01-23T14:45:33","slug":"forever-stack-me-ring-1as0125bb1140","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/","title":{"rendered":"Chimento FOREVER Stack Me Ring"},"content":{"rendered":"<div class=\"ql-block\" data-block-id=\"block-51c8584f-020b-422c-b74d-2b5eeb672326\">CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen.<\/div>\n<div class=\"ql-block\" data-block-id=\"block-a8cad885-79a6-4b80-a60d-ada01f97a2c4\"><\/div>\n<div class=\"ql-block\" data-block-id=\"block-de83b467-9e0c-4d66-86ab-a4262260e70f\">Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer Goldschmiedequalit\u00e4t und Botschafter des italienischen Schmucks in der ganzen Welt werden liessen.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen. Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/\" title=\"Read Chimento FOREVER Stack Me Ring\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":21268,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[189],"product_tag":[],"class_list":["post-21973","product","type-product","status-publish","has-post-thumbnail","schmuckhersteller-chimento","schmuckthemen-rings","product_cat-schmuck","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chimento FOREVER Stack Me Ring - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chimento FOREVER Stack Me Ring - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen. Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T14:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1AS0125BB1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/\",\"name\":\"Chimento FOREVER Stack Me Ring - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1AS0125BB1-1.png\",\"datePublished\":\"2023-11-08T20:46:56+00:00\",\"dateModified\":\"2026-01-23T14:45:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1AS0125BB1-1.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/1AS0125BB1-1.png\",\"width\":1000,\"height\":1400,\"caption\":\"Chimento-FOREVER Stack Me ring-zurich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/schmuck\\\/chimento\\\/forever-stack-me-ring-1as0125bb1140\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chimento FOREVER Stack Me Ring\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chimento FOREVER Stack Me Ring - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/","og_locale":"en_US","og_type":"article","og_title":"Chimento FOREVER Stack Me Ring - Galli Uhren Bijouterie","og_description":"CHIMENTO ist ein Synonym f\u00fcr Qualit\u00e4t und Exzellenz bei der Kreation einzigartiger Schmuckst\u00fccke mit zeitlosen Klassikern, die italienisches Gold in seiner besten Form zum Ausdruck bringen. Die Geschichte des Unternehmens beginnt 1964 im renommierten Juwelierviertel von Vicenza, wo das Gesp\u00fcr, die Leidenschaft und der Gesch\u00e4ftssinn des Gr\u00fcnders Adriano Chimento die Marke zu einem Interpreten italienischer... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-01-23T14:45:33+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1AS0125BB1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/","url":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/","name":"Chimento FOREVER Stack Me Ring - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1AS0125BB1-1.png","datePublished":"2023-11-08T20:46:56+00:00","dateModified":"2026-01-23T14:45:33+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1AS0125BB1-1.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/1AS0125BB1-1.png","width":1000,"height":1400,"caption":"Chimento-FOREVER Stack Me ring-zurich"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/schmuck\/chimento\/forever-stack-me-ring-1as0125bb1140\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Chimento FOREVER Stack Me Ring"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/21973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/21268"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=21973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=21973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=21973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=21973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}