{"id":1964,"date":"2018-07-31T02:16:30","date_gmt":"2018-07-31T02:16:30","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=1964"},"modified":"2026-06-01T10:18:19","modified_gmt":"2026-06-01T08:18:19","slug":"prestige-424-10-37-20-02-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/","title":{"rendered":"Omega Prestige Co-Axial 36,8"},"content":{"rendered":"<p>Die OMEGA De Ville Prestige-Kollektion konnte sich im Laufe der Jahre dank ihres klassisch-eleganten Designs eine gro\u00dfe und treue Anh\u00e4ngerschaft sichern.<\/p>\n<p>Diese Zeitmesser, die sich durch ihren reinen Stil mit luxuri\u00f6ser Endverarbeitung auszeichnen, verk\u00f6rpern ein zeitloses Design. Dieses Modell verf\u00fcgt \u00fcber ein bemerkenswertes, aus zwei voneinander abgesetzten Zonen bestehendes, silberfarbenes Zifferblatt mit r\u00f6mischen Ziffern bei 3, 6, 9 und 12 Uhr.<\/p>\n<p>Ein kratzresistentes Saphirglas sch\u00fctzt das eindrucksvolle Zifferblatt mit Datumsfenster bei 3 Uhr. Die L\u00fcnette ist auf einem 36,8-mm-Geh\u00e4use aus Edelstahl mit passendem Edelstahlarmband angebracht. Das Herzst\u00fcck dieses Zeitmessers bildet das Co-Axial Kaliber 2500.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die OMEGA De Ville Prestige-Kollektion konnte sich im Laufe der Jahre dank ihres klassisch-eleganten Designs eine gro\u00dfe und treue Anh\u00e4ngerschaft sichern. Diese Zeitmesser, die sich durch ihren reinen Stil mit luxuri\u00f6ser Endverarbeitung auszeichnen, verk\u00f6rpern ein zeitloses Design. Dieses Modell verf\u00fcgt \u00fcber ein bemerkenswertes, aus zwei voneinander abgesetzten Zonen bestehendes, silberfarbenes Zifferblatt mit r\u00f6mischen Ziffern bei&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/\" title=\"Read Omega Prestige Co-Axial 36,8\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":1890,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-1964","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-de-ville","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Prestige Co-Axial 36,8 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Prestige Co-Axial 36,8 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die OMEGA De Ville Prestige-Kollektion konnte sich im Laufe der Jahre dank ihres klassisch-eleganten Designs eine gro\u00dfe und treue Anh\u00e4ngerschaft sichern. Diese Zeitmesser, die sich durch ihren reinen Stil mit luxuri\u00f6ser Endverarbeitung auszeichnen, verk\u00f6rpern ein zeitloses Design. Dieses Modell verf\u00fcgt \u00fcber ein bemerkenswertes, aus zwei voneinander abgesetzten Zonen bestehendes, silberfarbenes Zifferblatt mit r\u00f6mischen Ziffern bei... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:18:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/424_10_37_20_02_001_small.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/\",\"name\":\"Omega Prestige Co-Axial 36,8 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/424_10_37_20_02_001_small.png\",\"datePublished\":\"2018-07-31T02:16:30+00:00\",\"dateModified\":\"2026-06-01T08:18:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/424_10_37_20_02_001_small.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/424_10_37_20_02_001_small.png\",\"width\":500,\"height\":700,\"caption\":\"Omega De Ville\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-424-10-37-20-02-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Prestige Co-Axial 36,8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Prestige Co-Axial 36,8 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Prestige Co-Axial 36,8 - Galli Uhren Bijouterie","og_description":"Die OMEGA De Ville Prestige-Kollektion konnte sich im Laufe der Jahre dank ihres klassisch-eleganten Designs eine gro\u00dfe und treue Anh\u00e4ngerschaft sichern. Diese Zeitmesser, die sich durch ihren reinen Stil mit luxuri\u00f6ser Endverarbeitung auszeichnen, verk\u00f6rpern ein zeitloses Design. Dieses Modell verf\u00fcgt \u00fcber ein bemerkenswertes, aus zwei voneinander abgesetzten Zonen bestehendes, silberfarbenes Zifferblatt mit r\u00f6mischen Ziffern bei... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:18:19+00:00","og_image":[{"width":500,"height":700,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/424_10_37_20_02_001_small.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/","name":"Omega Prestige Co-Axial 36,8 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/424_10_37_20_02_001_small.png","datePublished":"2018-07-31T02:16:30+00:00","dateModified":"2026-06-01T08:18:19+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/424_10_37_20_02_001_small.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/424_10_37_20_02_001_small.png","width":500,"height":700,"caption":"Omega De Ville"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-424-10-37-20-02-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Prestige Co-Axial 36,8"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/1964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/1890"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=1964"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=1964"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=1964"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=1964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}