{"id":19413,"date":"2023-06-29T18:23:06","date_gmt":"2023-06-29T16:23:06","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=19413"},"modified":"2026-06-01T10:13:30","modified_gmt":"2026-06-01T08:13:30","slug":"fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/","title":{"rendered":"Tudor Pelagos FXD Chrono"},"content":{"rendered":"<p>Die Pelagos FXD Chrono &#8220;Alinghi Red Bull Racing Edition&#8221; ist die erste Pelagos mit Chronographenfunktion. Der &#8220;Rumpf&#8221; der Uhr besteht aus einem 43-mm-Geh\u00e4use aus schwarzem Karbon mit mattem Finish und festen Bandstegen. Hinzu kommt eine bidirektionale 60-Minuten-L\u00fcnette aus Titan mit einem Einsatz aus mattschwarzem Karbonverbundstoff.<\/p>\n<p>2022 ging Tudor eine langfristige Partnerschaft mit Alinghi Red Bull Racing ein und wagte somit seine ersten Schritte in der Welt des professionellen Segelsports.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Pelagos FXD Chrono &#8220;Alinghi Red Bull Racing Edition&#8221; ist die erste Pelagos mit Chronographenfunktion. Der &#8220;Rumpf&#8221; der Uhr besteht aus einem 43-mm-Geh\u00e4use aus schwarzem Karbon mit mattem Finish und festen Bandstegen. Hinzu kommt eine bidirektionale 60-Minuten-L\u00fcnette aus Titan mit einem Einsatz aus mattschwarzem Karbonverbundstoff. 2022 ging Tudor eine langfristige Partnerschaft mit Alinghi Red Bull&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/\" title=\"Read Tudor Pelagos FXD Chrono\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":19411,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-19413","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tudor","uhrenhersteller-pelagos","product_cat-uhren","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tudor Tudor Pelagos FXD Chrono - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tudor Tudor Pelagos FXD Chrono - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Pelagos FXD Chrono &#8220;Alinghi Red Bull Racing Edition&#8221; ist die erste Pelagos mit Chronographenfunktion. Der &#8220;Rumpf&#8221; der Uhr besteht aus einem 43-mm-Geh\u00e4use aus schwarzem Karbon mit mattem Finish und festen Bandstegen. Hinzu kommt eine bidirektionale 60-Minuten-L\u00fcnette aus Titan mit einem Einsatz aus mattschwarzem Karbonverbundstoff. 2022 ging Tudor eine langfristige Partnerschaft mit Alinghi Red Bull... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m25807kn-0001.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/\",\"name\":\"Tudor Tudor Pelagos FXD Chrono - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m25807kn-0001.png\",\"datePublished\":\"2023-06-29T16:23:06+00:00\",\"dateModified\":\"2026-06-01T08:13:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m25807kn-0001.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m25807kn-0001.png\",\"width\":1000,\"height\":1400,\"caption\":\"tudor-pelagos-fxd-chrono-m25807kn-0001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/pelagos\\\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pelagos FXD Chrono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tudor Tudor Pelagos FXD Chrono - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/","og_locale":"en_US","og_type":"article","og_title":"Tudor Tudor Pelagos FXD Chrono - Galli Uhren Bijouterie","og_description":"Die Pelagos FXD Chrono &#8220;Alinghi Red Bull Racing Edition&#8221; ist die erste Pelagos mit Chronographenfunktion. Der &#8220;Rumpf&#8221; der Uhr besteht aus einem 43-mm-Geh\u00e4use aus schwarzem Karbon mit mattem Finish und festen Bandstegen. Hinzu kommt eine bidirektionale 60-Minuten-L\u00fcnette aus Titan mit einem Einsatz aus mattschwarzem Karbonverbundstoff. 2022 ging Tudor eine langfristige Partnerschaft mit Alinghi Red Bull... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:13:30+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m25807kn-0001.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/","name":"Tudor Tudor Pelagos FXD Chrono - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m25807kn-0001.png","datePublished":"2023-06-29T16:23:06+00:00","dateModified":"2026-06-01T08:13:30+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m25807kn-0001.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m25807kn-0001.png","width":1000,"height":1400,"caption":"tudor-pelagos-fxd-chrono-m25807kn-0001"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/pelagos\/fxd-chrono-alinghi-red-bull-racing-edition-m25807kn-0001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Pelagos FXD Chrono"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/19413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/19411"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=19413"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=19413"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=19413"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=19413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}