{"id":16296,"date":"2022-11-18T14:43:22","date_gmt":"2022-11-18T13:43:22","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=product&#038;p=16296"},"modified":"2026-06-01T10:14:34","modified_gmt":"2026-06-01T08:14:34","slug":"prestige-co-axial-master-chronometer-34-434-10-34-20-05-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/","title":{"rendered":"Omega Prestige Co-Axial Master Chronometer 34"},"content":{"rendered":"<p>Die OMEGA De Ville Prestige, eine zeitlose Kollektion seit 1994, wird nun in ihrer dritten Generation hergestellt. Die Zeitmesser, die weiterhin f\u00fcr klassisches Design und raffinierte Eleganz stehen, bieten eine Reihe von Mustern, Veredelungen und Farben, die zu verschiedenen Lebensstilen und Pers\u00f6nlichkeiten passen.<\/p>\n<p>Bei diesem Modell aus Edelstahl (34 mm) ist das Zifferblatt aus weissem Perlmutt gefertigt. Die Anzeige zeichnet sich durch PVD Sedna\u2122 Gold gef\u00e4rbte Zeiger sowie abwechselnd r\u00f6mische Ziffern und Cabochon-Indizes aus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die OMEGA De Ville Prestige, eine zeitlose Kollektion seit 1994, wird nun in ihrer dritten Generation hergestellt. Die Zeitmesser, die weiterhin f\u00fcr klassisches Design und raffinierte Eleganz stehen, bieten eine Reihe von Mustern, Veredelungen und Farben, die zu verschiedenen Lebensstilen und Pers\u00f6nlichkeiten passen. Bei diesem Modell aus Edelstahl (34 mm) ist das Zifferblatt aus weissem&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/\" title=\"Read Omega Prestige Co-Axial Master Chronometer 34\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":16133,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-16296","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-de-ville","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Prestige Co-Axial Master Chronometer 34 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Prestige Co-Axial Master Chronometer 34 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die OMEGA De Ville Prestige, eine zeitlose Kollektion seit 1994, wird nun in ihrer dritten Generation hergestellt. Die Zeitmesser, die weiterhin f\u00fcr klassisches Design und raffinierte Eleganz stehen, bieten eine Reihe von Mustern, Veredelungen und Farben, die zu verschiedenen Lebensstilen und Pers\u00f6nlichkeiten passen. Bei diesem Modell aus Edelstahl (34 mm) ist das Zifferblatt aus weissem... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/\",\"name\":\"Omega Prestige Co-Axial Master Chronometer 34 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png\",\"datePublished\":\"2022-11-18T13:43:22+00:00\",\"dateModified\":\"2026-06-01T08:14:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png\",\"width\":1000,\"height\":1400,\"caption\":\"omega-de-ville-prestige\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/de-ville\\\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Prestige Co-Axial Master Chronometer 34\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Prestige Co-Axial Master Chronometer 34 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Prestige Co-Axial Master Chronometer 34 - Galli Uhren Bijouterie","og_description":"Die OMEGA De Ville Prestige, eine zeitlose Kollektion seit 1994, wird nun in ihrer dritten Generation hergestellt. Die Zeitmesser, die weiterhin f\u00fcr klassisches Design und raffinierte Eleganz stehen, bieten eine Reihe von Mustern, Veredelungen und Farben, die zu verschiedenen Lebensstilen und Pers\u00f6nlichkeiten passen. Bei diesem Modell aus Edelstahl (34 mm) ist das Zifferblatt aus weissem... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:14:34+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/","name":"Omega Prestige Co-Axial Master Chronometer 34 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png","datePublished":"2022-11-18T13:43:22+00:00","dateModified":"2026-06-01T08:14:34+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-de-ville-prestige-co-axial-master-chronometer-34-mm-43410342005001-1-product-zoom.png","width":1000,"height":1400,"caption":"omega-de-ville-prestige"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/de-ville\/prestige-co-axial-master-chronometer-34-434-10-34-20-05-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Prestige Co-Axial Master Chronometer 34"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/16296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/16133"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=16296"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=16296"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=16296"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=16296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}