{"id":13306,"date":"2022-03-30T18:17:05","date_gmt":"2022-03-30T16:17:05","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=13306"},"modified":"2026-06-01T10:15:31","modified_gmt":"2026-06-01T08:15:31","slug":"m79470-0003","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/tudor\/black-bay-pro\/m79470-0003\/","title":{"rendered":"Tudor Black Bay Pro"},"content":{"rendered":"<p>Die Black Bay Pro hat einen Durchmesser von 39 Millimeter, eine feststehende L\u00fcnette in Edelstahl und ein Manufakturwerk mit eingebauter GMT\u2011Funktion.<\/p>\n<p>Bei dieser Uhr wird die Referenzzeit durch einen eckigen gelben Snowflake-Zeiger angezeigt \u2013 ein \u00e4sthetisches Markenzeichen von TUDOR \u2013 der innerhalb von 24 Stunden einmal das gesamte Zifferblatt umrundet. Die Lokalzeit wird durch einen weiteren k\u00fcrzeren Snowflake-Zeiger angegeben, der durch eine springende Stunde eingestellt und in beide Richtungen bewegt werden kann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Black Bay Pro hat einen Durchmesser von 39 Millimeter, eine feststehende L\u00fcnette in Edelstahl und ein Manufakturwerk mit eingebauter GMT\u2011Funktion. Bei dieser Uhr wird die Referenzzeit durch einen eckigen gelben Snowflake-Zeiger angezeigt \u2013 ein \u00e4sthetisches Markenzeichen von TUDOR \u2013 der innerhalb von 24 Stunden einmal das gesamte Zifferblatt umrundet. Die Lokalzeit wird durch einen&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/tudor\/black-bay-pro\/m79470-0003\/\" title=\"Read Tudor Black Bay Pro\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":13290,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[191],"class_list":["post-13306","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-tudor","uhrenhersteller-black-bay-pro","product_cat-uhren","product_tag-update","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tudor Black Bay Pro - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tudor Black Bay Pro - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Black Bay Pro hat einen Durchmesser von 39 Millimeter, eine feststehende L\u00fcnette in Edelstahl und ein Manufakturwerk mit eingebauter GMT\u2011Funktion. Bei dieser Uhr wird die Referenzzeit durch einen eckigen gelben Snowflake-Zeiger angezeigt \u2013 ein \u00e4sthetisches Markenzeichen von TUDOR \u2013 der innerhalb von 24 Stunden einmal das gesamte Zifferblatt umrundet. Die Lokalzeit wird durch einen... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m79470-0003.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/\",\"name\":\"Tudor Black Bay Pro - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m79470-0003.png\",\"datePublished\":\"2022-03-30T16:17:05+00:00\",\"dateModified\":\"2026-06-01T08:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m79470-0003.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/tudor-m79470-0003.png\",\"width\":1000,\"height\":1400,\"caption\":\"tudor-black-bay-pro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/tudor\\\/black-bay-pro\\\/m79470-0003\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tudor Black Bay Pro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tudor Black Bay Pro - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/","og_locale":"en_US","og_type":"article","og_title":"Tudor Black Bay Pro - Galli Uhren Bijouterie","og_description":"Die Black Bay Pro hat einen Durchmesser von 39 Millimeter, eine feststehende L\u00fcnette in Edelstahl und ein Manufakturwerk mit eingebauter GMT\u2011Funktion. Bei dieser Uhr wird die Referenzzeit durch einen eckigen gelben Snowflake-Zeiger angezeigt \u2013 ein \u00e4sthetisches Markenzeichen von TUDOR \u2013 der innerhalb von 24 Stunden einmal das gesamte Zifferblatt umrundet. Die Lokalzeit wird durch einen... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:15:31+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m79470-0003.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/","url":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/","name":"Tudor Black Bay Pro - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m79470-0003.png","datePublished":"2022-03-30T16:17:05+00:00","dateModified":"2026-06-01T08:15:31+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m79470-0003.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/tudor-m79470-0003.png","width":1000,"height":1400,"caption":"tudor-black-bay-pro"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/tudor\/black-bay-pro\/m79470-0003\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Tudor Black Bay Pro"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/13306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/13290"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=13306"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=13306"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=13306"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=13306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}