{"id":13020,"date":"2022-03-10T11:35:55","date_gmt":"2022-03-10T09:35:55","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=13020"},"modified":"2026-06-01T10:18:17","modified_gmt":"2026-06-01T08:18:17","slug":"57-master-chronometer-332-12-41-51-11-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/","title":{"rendered":"Omega Speedmaster 57 Master Chronometer"},"content":{"rendered":"<p>Die Speedmaster ist einer der ikonischsten Zeitmesser der Marke OMEGA. Der Chronograph war Teil aller sechs Mondlandungen und repr\u00e4sentiert auf eindrucksvolle Weise den Abenteuer- und Pioniergeist der Marke.<\/p>\n<p>Dieses 40,5mm-Modell, das von dem legend\u00e4ren Original aus dem Jahr 1957 inspiriert ist, besitzt ein Geh\u00e4use aus Edelstahl und ein burgunderrotes Zifferblatt mit vertieften Stundenindizes und Vintage-Super-LumiNova. Neben den rhodinierten \u201eBroad-Arrow\u201c-Zeigern sind bei 6 Uhr ein Datumsfenster, bei 9 Uhr ein Hilfszifferblatt f\u00fcr die kleine Sekunde und bei 3 Uhr ein 12-Stunden- und ein 60-Minuten-Chronographenz\u00e4hler zu sehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Speedmaster ist einer der ikonischsten Zeitmesser der Marke OMEGA. Der Chronograph war Teil aller sechs Mondlandungen und repr\u00e4sentiert auf eindrucksvolle Weise den Abenteuer- und Pioniergeist der Marke. Dieses 40,5mm-Modell, das von dem legend\u00e4ren Original aus dem Jahr 1957 inspiriert ist, besitzt ein Geh\u00e4use aus Edelstahl und ein burgunderrotes Zifferblatt mit vertieften Stundenindizes und Vintage-Super-LumiNova&#8230;.  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/\" title=\"Read Omega Speedmaster 57 Master Chronometer\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":12956,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-13020","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-speedmaster","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Speedmaster 57 Master Chronometer - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Speedmaster 57 Master Chronometer - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Speedmaster ist einer der ikonischsten Zeitmesser der Marke OMEGA. Der Chronograph war Teil aller sechs Mondlandungen und repr\u00e4sentiert auf eindrucksvolle Weise den Abenteuer- und Pioniergeist der Marke. Dieses 40,5mm-Modell, das von dem legend\u00e4ren Original aus dem Jahr 1957 inspiriert ist, besitzt ein Geh\u00e4use aus Edelstahl und ein burgunderrotes Zifferblatt mit vertieften Stundenindizes und Vintage-Super-LumiNova.... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:18:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/OME392_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/\",\"name\":\"Omega Speedmaster 57 Master Chronometer - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/OME392_1.png\",\"datePublished\":\"2022-03-10T09:35:55+00:00\",\"dateModified\":\"2026-06-01T08:18:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/OME392_1.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/OME392_1.png\",\"width\":1000,\"height\":1400,\"caption\":\"speedmaster-57-master-chronometer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/speedmaster\\\/57-master-chronometer-332-12-41-51-11-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Speedmaster 57 Master Chronometer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Speedmaster 57 Master Chronometer - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Speedmaster 57 Master Chronometer - Galli Uhren Bijouterie","og_description":"Die Speedmaster ist einer der ikonischsten Zeitmesser der Marke OMEGA. Der Chronograph war Teil aller sechs Mondlandungen und repr\u00e4sentiert auf eindrucksvolle Weise den Abenteuer- und Pioniergeist der Marke. Dieses 40,5mm-Modell, das von dem legend\u00e4ren Original aus dem Jahr 1957 inspiriert ist, besitzt ein Geh\u00e4use aus Edelstahl und ein burgunderrotes Zifferblatt mit vertieften Stundenindizes und Vintage-Super-LumiNova.... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:18:17+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/OME392_1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/","name":"Omega Speedmaster 57 Master Chronometer - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/OME392_1.png","datePublished":"2022-03-10T09:35:55+00:00","dateModified":"2026-06-01T08:18:17+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/OME392_1.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/OME392_1.png","width":1000,"height":1400,"caption":"speedmaster-57-master-chronometer"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/speedmaster\/57-master-chronometer-332-12-41-51-11-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Speedmaster 57 Master Chronometer"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/13020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/12956"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=13020"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=13020"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=13020"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=13020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}