{"id":1277,"date":"2018-07-25T19:01:58","date_gmt":"2018-07-25T17:01:58","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=1277"},"modified":"2026-06-01T10:10:04","modified_gmt":"2026-06-01T08:10:04","slug":"b01-chronograph-ab0119131c1p1","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/","title":{"rendered":"Breitling Aviator 8 B01 Chronograph"},"content":{"rendered":"<p>Die Navitimer 8 B01 Chronograph 43 wird durch das hauseigene Breitling Manufaktur Caliber 01 betrieben. Die 43-mm-Automatikuhr verf\u00fcgt \u00fcber einen Sperrrad-Chronographen mit vertikaler Kupplung und einer beeindruckenden Gangreserve von \u00fcber 70 Stunden. Die Anzeige verf\u00fcgt \u00fcber 30-Minuten- und 12-Stunden-Z\u00e4hler sowie ein Datumsfenster. Die Navitimer 8 B01 Chronograph 43 ist das Highlight dieser neuen Reihe und in Stahl mit schwarzem oder blauem Ziffernblatt oder in 18-kar\u00e4tigem Rotgold mit Bronze-Ziffernblatt erh\u00e4ltlich. Auf allen Varianten sind markante Design-Elemente der sich voneinander abhebenden kleineren Ziffernbl\u00e4ttern vorhanden. Dieser COSC-zertifizierte Chronometer sitzt auf einem Stahl-Armband oder einem Band aus Alligatorleder und verf\u00fcgt \u00fcber einen transparenten Saphirglas-Geh\u00e4user\u00fccken.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Navitimer 8 B01 Chronograph 43 wird durch das hauseigene Breitling Manufaktur Caliber 01 betrieben. Die 43-mm-Automatikuhr verf\u00fcgt \u00fcber einen Sperrrad-Chronographen mit vertikaler Kupplung und einer beeindruckenden Gangreserve von \u00fcber 70 Stunden. Die Anzeige verf\u00fcgt \u00fcber 30-Minuten- und 12-Stunden-Z\u00e4hler sowie ein Datumsfenster. Die Navitimer 8 B01 Chronograph 43 ist das Highlight dieser neuen Reihe und&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/\" title=\"Read Breitling Aviator 8 B01 Chronograph\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":1238,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-1277","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-breitling","uhrenhersteller-classic-avi","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Breitling Aviator 8 B01 Chronograph - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breitling Aviator 8 B01 Chronograph - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Die Navitimer 8 B01 Chronograph 43 wird durch das hauseigene Breitling Manufaktur Caliber 01 betrieben. Die 43-mm-Automatikuhr verf\u00fcgt \u00fcber einen Sperrrad-Chronographen mit vertikaler Kupplung und einer beeindruckenden Gangreserve von \u00fcber 70 Stunden. Die Anzeige verf\u00fcgt \u00fcber 30-Minuten- und 12-Stunden-Z\u00e4hler sowie ein Datumsfenster. Die Navitimer 8 B01 Chronograph 43 ist das Highlight dieser neuen Reihe und... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T08:10:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/\",\"name\":\"Breitling Aviator 8 B01 Chronograph - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png\",\"datePublished\":\"2018-07-25T17:01:58+00:00\",\"dateModified\":\"2026-06-01T08:10:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png\",\"width\":1000,\"height\":1400,\"caption\":\"Breitling Navitimer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/breitling\\\/classic-avi\\\/b01-chronograph-ab0119131c1p1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aviator 8 B01 Chronograph\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breitling Aviator 8 B01 Chronograph - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/","og_locale":"en_US","og_type":"article","og_title":"Breitling Aviator 8 B01 Chronograph - Galli Uhren Bijouterie","og_description":"Die Navitimer 8 B01 Chronograph 43 wird durch das hauseigene Breitling Manufaktur Caliber 01 betrieben. Die 43-mm-Automatikuhr verf\u00fcgt \u00fcber einen Sperrrad-Chronographen mit vertikaler Kupplung und einer beeindruckenden Gangreserve von \u00fcber 70 Stunden. Die Anzeige verf\u00fcgt \u00fcber 30-Minuten- und 12-Stunden-Z\u00e4hler sowie ein Datumsfenster. Die Navitimer 8 B01 Chronograph 43 ist das Highlight dieser neuen Reihe und... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-06-01T08:10:04+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/","url":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/","name":"Breitling Aviator 8 B01 Chronograph - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png","datePublished":"2018-07-25T17:01:58+00:00","dateModified":"2026-06-01T08:10:04+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/Navitimer-8-B01-with-blue-dial-and-black-alligator-leather-strap.png","width":1000,"height":1400,"caption":"Breitling Navitimer"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/breitling\/classic-avi\/b01-chronograph-ab0119131c1p1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Aviator 8 B01 Chronograph"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/1277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/1238"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=1277"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=1277"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=1277"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=1277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}