{"id":12044,"date":"2021-12-02T13:46:48","date_gmt":"2021-12-02T11:46:48","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=12044"},"modified":"2026-03-02T12:29:43","modified_gmt":"2026-03-02T11:29:43","slug":"master-chronometer-34mm-131-28-34-20-55-001","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/","title":{"rendered":"Omega Constellation Master Chronometer 34"},"content":{"rendered":"<p>Das spektakul\u00e4re und langlebige Design der OMEGA Constellation zeichnet sich durch die ber\u00fchmten Halbmondfacetten sowie die \u201eKrappen\u201c an der Geh\u00e4useseite aus.<\/p>\n<p>Dieses 34 mm grosse Modell aus 18 K Sedna\u2122-Gold und Edelstahl verf\u00fcgt \u00fcber eine mit Diamanten besetzte L\u00fcnette, ein mattweisses Perlmuttzifferblatt und ein rundes Datumsfenster bei 6 Uhr. Die zulaufenden Diamantstundenindizes verf\u00fcgen \u00fcber Fassungen aus 18 K Sedna\u2122-Gold. Der Ring rund um das Hilfszifferblatt f\u00fcr die kleine Sekunde besteht ebenfalls aus 18 K Sedna\u2122-Gold und ist mit Diamanten besetzt.<\/p>\n<p>Angetrieben wird dieser Zeitmesser mit beigefarbenem Lederarmband von dem OMEGA Co-Axial Master Chronometer Kaliber 8802, das durch das gew\u00f6lbte kratzresistente Saphirglas sichtbar ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das spektakul\u00e4re und langlebige Design der OMEGA Constellation zeichnet sich durch die ber\u00fchmten Halbmondfacetten sowie die \u201eKrappen\u201c an der Geh\u00e4useseite aus. Dieses 34 mm grosse Modell aus 18 K Sedna\u2122-Gold und Edelstahl verf\u00fcgt \u00fcber eine mit Diamanten besetzte L\u00fcnette, ein mattweisses Perlmuttzifferblatt und ein rundes Datumsfenster bei 6 Uhr. Die zulaufenden Diamantstundenindizes verf\u00fcgen \u00fcber Fassungen&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/\" title=\"Read Omega Constellation Master Chronometer 34\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":12030,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-12044","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-omega","uhrenhersteller-constellation","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omega Constellation Master Chronometer 34 - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omega Constellation Master Chronometer 34 - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Das spektakul\u00e4re und langlebige Design der OMEGA Constellation zeichnet sich durch die ber\u00fchmten Halbmondfacetten sowie die \u201eKrappen\u201c an der Geh\u00e4useseite aus. Dieses 34 mm grosse Modell aus 18 K Sedna\u2122-Gold und Edelstahl verf\u00fcgt \u00fcber eine mit Diamanten besetzte L\u00fcnette, ein mattweisses Perlmuttzifferblatt und ein rundes Datumsfenster bei 6 Uhr. Die zulaufenden Diamantstundenindizes verf\u00fcgen \u00fcber Fassungen... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T11:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/\",\"name\":\"Omega Constellation Master Chronometer 34 - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png\",\"datePublished\":\"2021-12-02T11:46:48+00:00\",\"dateModified\":\"2026-03-02T11:29:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png\",\"width\":1000,\"height\":1400,\"caption\":\"omega-constellation-small-seconds-zurich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/omega\\\/constellation\\\/master-chronometer-34mm-131-28-34-20-55-001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Omega Constellation Master Chronometer 34\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omega Constellation Master Chronometer 34 - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/","og_locale":"en_US","og_type":"article","og_title":"Omega Constellation Master Chronometer 34 - Galli Uhren Bijouterie","og_description":"Das spektakul\u00e4re und langlebige Design der OMEGA Constellation zeichnet sich durch die ber\u00fchmten Halbmondfacetten sowie die \u201eKrappen\u201c an der Geh\u00e4useseite aus. Dieses 34 mm grosse Modell aus 18 K Sedna\u2122-Gold und Edelstahl verf\u00fcgt \u00fcber eine mit Diamanten besetzte L\u00fcnette, ein mattweisses Perlmuttzifferblatt und ein rundes Datumsfenster bei 6 Uhr. Die zulaufenden Diamantstundenindizes verf\u00fcgen \u00fcber Fassungen... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2026-03-02T11:29:43+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/","url":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/","name":"Omega Constellation Master Chronometer 34 - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png","datePublished":"2021-12-02T11:46:48+00:00","dateModified":"2026-03-02T11:29:43+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/omega-constellation-co-axial-master-chronometer-small-seconds-34-mm-13128342055001-1-product-zoom-1.png","width":1000,"height":1400,"caption":"omega-constellation-small-seconds-zurich"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/omega\/constellation\/master-chronometer-34mm-131-28-34-20-55-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Omega Constellation Master Chronometer 34"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/12044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/12030"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=12044"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=12044"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=12044"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=12044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}