{"id":11335,"date":"2021-09-27T17:30:17","date_gmt":"2021-09-27T15:30:17","guid":{"rendered":"https:\/\/galli.testkopie.dev\/?post_type=uhren&#038;p=11335"},"modified":"2025-03-13T13:44:37","modified_gmt":"2025-03-13T12:44:37","slug":"automatic-chronograph-sprint-ai6038-dlb01-330-4","status":"publish","type":"product","link":"https:\/\/galli.testkopie.dev\/en\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/","title":{"rendered":"Maurice Lacroix Aikon Automatic Chronograph Sprint"},"content":{"rendered":"<p>Der AIKON Automatic Chronograph Sprint spielt mit Farben und Texturen und verleiht dem Modell ein Erscheinungsbild, das sich von denen der bisherigen Chronographen-Modelle stark unterscheidet. Doch die Design-Codes bleiben bestehen: Auch dieses neue Modell verf\u00fcgt weiterhin \u00fcber die charakteristischen sechs Arme an der L\u00fcnette, das M-Logo auf dem Armband und den urbanen Stil der AIKON.<\/p>\n<p>Einfach ausgedr\u00fcckt, zeigt sich das neue Modell modern und sportlich, steht aber voll und ganz im Einklang mit dem Verm\u00e4chtnis der Reihe. Sie ist weltweit auf 500 Exemplare limitiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der AIKON Automatic Chronograph Sprint spielt mit Farben und Texturen und verleiht dem Modell ein Erscheinungsbild, das sich von denen der bisherigen Chronographen-Modelle stark unterscheidet. Doch die Design-Codes bleiben bestehen: Auch dieses neue Modell verf\u00fcgt weiterhin \u00fcber die charakteristischen sechs Arme an der L\u00fcnette, das M-Logo auf dem Armband und den urbanen Stil der AIKON&#8230;.  <a class=\"excerpt-read-more\" href=\"https:\/\/galli.testkopie.dev\/en\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/\" title=\"Read Maurice Lacroix Aikon Automatic Chronograph Sprint\">Weiter &raquo;<\/a><\/p>\n","protected":false},"featured_media":11166,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[188],"product_tag":[],"class_list":["post-11335","product","type-product","status-publish","has-post-thumbnail","uhrenhersteller-aikon","uhrenhersteller-maurice-lacroix","product_cat-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maurice Lacroix Aikon Automatic Chronograph Sprint - Galli Uhren Bijouterie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maurice Lacroix Aikon Automatic Chronograph Sprint - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Der AIKON Automatic Chronograph Sprint spielt mit Farben und Texturen und verleiht dem Modell ein Erscheinungsbild, das sich von denen der bisherigen Chronographen-Modelle stark unterscheidet. Doch die Design-Codes bleiben bestehen: Auch dieses neue Modell verf\u00fcgt weiterhin \u00fcber die charakteristischen sechs Arme an der L\u00fcnette, das M-Logo auf dem Armband und den urbanen Stil der AIKON.... Weiter &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T12:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/ai6038_dlb01_330_4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/\",\"name\":\"Maurice Lacroix Aikon Automatic Chronograph Sprint - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/ai6038_dlb01_330_4.png\",\"datePublished\":\"2021-09-27T15:30:17+00:00\",\"dateModified\":\"2025-03-13T12:44:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/ai6038_dlb01_330_4.png\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/ai6038_dlb01_330_4.png\",\"width\":1000,\"height\":1400,\"caption\":\"Aikon Automatic Chronograph Sprint\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/uhren\\\/maurice-lacroix\\\/aikon\\\/automatic-chronograph-sprint-ai6038-dlb01-330-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uhren\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/uhren\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aikon Automatic Chronograph Sprint\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maurice Lacroix Aikon Automatic Chronograph Sprint - Galli Uhren Bijouterie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/","og_locale":"en_US","og_type":"article","og_title":"Maurice Lacroix Aikon Automatic Chronograph Sprint - Galli Uhren Bijouterie","og_description":"Der AIKON Automatic Chronograph Sprint spielt mit Farben und Texturen und verleiht dem Modell ein Erscheinungsbild, das sich von denen der bisherigen Chronographen-Modelle stark unterscheidet. Doch die Design-Codes bleiben bestehen: Auch dieses neue Modell verf\u00fcgt weiterhin \u00fcber die charakteristischen sechs Arme an der L\u00fcnette, das M-Logo auf dem Armband und den urbanen Stil der AIKON.... Weiter &raquo;","og_url":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/","og_site_name":"Galli Uhren Bijouterie","article_modified_time":"2025-03-13T12:44:37+00:00","og_image":[{"width":1000,"height":1400,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/ai6038_dlb01_330_4.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/","url":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/","name":"Maurice Lacroix Aikon Automatic Chronograph Sprint - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/ai6038_dlb01_330_4.png","datePublished":"2021-09-27T15:30:17+00:00","dateModified":"2025-03-13T12:44:37+00:00","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/ai6038_dlb01_330_4.png","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/ai6038_dlb01_330_4.png","width":1000,"height":1400,"caption":"Aikon Automatic Chronograph Sprint"},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/uhren\/maurice-lacroix\/aikon\/automatic-chronograph-sprint-ai6038-dlb01-330-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"Uhren","item":"https:\/\/galli.testkopie.dev\/en\/uhren\/"},{"@type":"ListItem","position":3,"name":"Aikon Automatic Chronograph Sprint"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product\/11335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/11166"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=11335"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_brand?post=11335"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_cat?post=11335"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/product_tag?post=11335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}