{"id":30316,"date":"2024-02-01T14:28:25","date_gmt":"2024-02-01T13:28:25","guid":{"rendered":"https:\/\/galli.testkopie.dev\/tudor-manufaktur\/"},"modified":"2024-04-02T13:22:40","modified_gmt":"2024-04-02T11:22:40","slug":"tudor-manufaktur","status":"publish","type":"post","link":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/","title":{"rendered":"The origins of the TUDOR manufacture"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":23383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-30316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The origins of the TUDOR manufacture - Galli Uhren Bijouterie<\/title>\n<meta name=\"description\" content=\"Der im Jahr 1926 gegr\u00fcndete Uhrenhersteller TUDOR er\u00f6ffnete im Jahr 2023 seine neue Manufaktur in Le Locle. Jetzt bei Galli Lesen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The origins of the TUDOR manufacture - Galli Uhren Bijouterie\" \/>\n<meta property=\"og:description\" content=\"Der im Jahr 1926 gegr\u00fcndete Uhrenhersteller TUDOR er\u00f6ffnete im Jahr 2023 seine neue Manufaktur in Le Locle. Jetzt bei Galli Lesen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/\" \/>\n<meta property=\"og:site_name\" content=\"Galli Uhren Bijouterie\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T13:28:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T11:22:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t<meta property=\"og:image:height\" content=\"1401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bryan Gablinger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/\"},\"author\":{\"name\":\"Bryan Gablinger\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#\\\/schema\\\/person\\\/2d8ea989f74da15795fceb13ca942b22\"},\"headline\":\"The origins of the TUDOR manufacture\",\"datePublished\":\"2024-02-01T13:28:25+00:00\",\"dateModified\":\"2024-04-02T11:22:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/\"},\"wordCount\":6,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/\",\"name\":\"The origins of the TUDOR manufacture - Galli Uhren Bijouterie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg\",\"datePublished\":\"2024-02-01T13:28:25+00:00\",\"dateModified\":\"2024-04-02T11:22:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#\\\/schema\\\/person\\\/2d8ea989f74da15795fceb13ca942b22\"},\"description\":\"Der im Jahr 1926 gegr\u00fcndete Uhrenhersteller TUDOR er\u00f6ffnete im Jahr 2023 seine neue Manufaktur in Le Locle. Jetzt bei Galli Lesen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg\",\"contentUrl\":\"https:\\\/\\\/galli.testkopie.dev\\\/wp-content\\\/uploads\\\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg\",\"width\":2100,\"height\":1401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/tudor-manufaktur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The origins of the TUDOR manufacture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/\",\"name\":\"Galli Uhren Bijouterie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/galli.testkopie.dev\\\/en\\\/#\\\/schema\\\/person\\\/2d8ea989f74da15795fceb13ca942b22\",\"name\":\"Bryan Gablinger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f8d5548604a7617a13e31864be50afd20583643bbf27aa9e659fe75ea5c8ade?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f8d5548604a7617a13e31864be50afd20583643bbf27aa9e659fe75ea5c8ade?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f8d5548604a7617a13e31864be50afd20583643bbf27aa9e659fe75ea5c8ade?s=96&d=mm&r=g\",\"caption\":\"Bryan Gablinger\"},\"sameAs\":[\"https:\\\/\\\/galli.testkopie.dev\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The origins of the TUDOR manufacture - Galli Uhren Bijouterie","description":"Der im Jahr 1926 gegr\u00fcndete Uhrenhersteller TUDOR er\u00f6ffnete im Jahr 2023 seine neue Manufaktur in Le Locle. Jetzt bei Galli Lesen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/","og_locale":"en_US","og_type":"article","og_title":"The origins of the TUDOR manufacture - Galli Uhren Bijouterie","og_description":"Der im Jahr 1926 gegr\u00fcndete Uhrenhersteller TUDOR er\u00f6ffnete im Jahr 2023 seine neue Manufaktur in Le Locle. Jetzt bei Galli Lesen.","og_url":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/","og_site_name":"Galli Uhren Bijouterie","article_published_time":"2024-02-01T13:28:25+00:00","article_modified_time":"2024-04-02T11:22:40+00:00","og_image":[{"width":2100,"height":1401,"url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg","type":"image\/jpeg"}],"author":"Bryan Gablinger","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#article","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/"},"author":{"name":"Bryan Gablinger","@id":"https:\/\/galli.testkopie.dev\/en\/#\/schema\/person\/2d8ea989f74da15795fceb13ca942b22"},"headline":"The origins of the TUDOR manufacture","datePublished":"2024-02-01T13:28:25+00:00","dateModified":"2024-04-02T11:22:40+00:00","mainEntityOfPage":{"@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/"},"wordCount":6,"commentCount":0,"image":{"@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/","url":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/","name":"The origins of the TUDOR manufacture - Galli Uhren Bijouterie","isPartOf":{"@id":"https:\/\/galli.testkopie.dev\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#primaryimage"},"image":{"@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#primaryimage"},"thumbnailUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg","datePublished":"2024-02-01T13:28:25+00:00","dateModified":"2024-04-02T11:22:40+00:00","author":{"@id":"https:\/\/galli.testkopie.dev\/en\/#\/schema\/person\/2d8ea989f74da15795fceb13ca942b22"},"description":"Der im Jahr 1926 gegr\u00fcndete Uhrenhersteller TUDOR er\u00f6ffnete im Jahr 2023 seine neue Manufaktur in Le Locle. Jetzt bei Galli Lesen.","breadcrumb":{"@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#primaryimage","url":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg","contentUrl":"https:\/\/galli.testkopie.dev\/wp-content\/uploads\/TUDOR-Manufaktur-Le-Locle-Schweiz-Fassaden-1.jpg","width":2100,"height":1401},{"@type":"BreadcrumbList","@id":"https:\/\/galli.testkopie.dev\/en\/tudor-manufaktur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galli.testkopie.dev\/en\/"},{"@type":"ListItem","position":2,"name":"The origins of the TUDOR manufacture"}]},{"@type":"WebSite","@id":"https:\/\/galli.testkopie.dev\/en\/#website","url":"https:\/\/galli.testkopie.dev\/en\/","name":"Galli Uhren Bijouterie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galli.testkopie.dev\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/galli.testkopie.dev\/en\/#\/schema\/person\/2d8ea989f74da15795fceb13ca942b22","name":"Bryan Gablinger","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4f8d5548604a7617a13e31864be50afd20583643bbf27aa9e659fe75ea5c8ade?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f8d5548604a7617a13e31864be50afd20583643bbf27aa9e659fe75ea5c8ade?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f8d5548604a7617a13e31864be50afd20583643bbf27aa9e659fe75ea5c8ade?s=96&d=mm&r=g","caption":"Bryan Gablinger"},"sameAs":["https:\/\/galli.testkopie.dev"]}]}},"_links":{"self":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/posts\/30316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/comments?post=30316"}],"version-history":[{"count":0,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/posts\/30316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media\/23383"}],"wp:attachment":[{"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/media?parent=30316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/categories?post=30316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/galli.testkopie.dev\/en\/wp-json\/wp\/v2\/tags?post=30316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}